{"id":3494,"date":"2026-04-17T09:49:12","date_gmt":"2026-04-17T09:49:12","guid":{"rendered":"https:\/\/www.rosesrentals.com\/?p=3494"},"modified":"2026-05-12T14:20:56","modified_gmt":"2026-05-12T14:20:56","slug":"el-bulli-cala-montjoi","status":"publish","type":"post","link":"https:\/\/www.rosesrentals.com\/nl\/el-bulli-cala-montjoi\/","title":{"rendered":"El Bulli Foundation in Cala Montjoi \u2013 Bezoek en lunch aan de Costa Brava"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3494\" class=\"elementor elementor-3494\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dbd17df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbd17df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-efc1b7b\" data-id=\"efc1b7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9833e15 elementor-widget elementor-widget-text-editor\" data-id=\"9833e15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 quelques kilom\u00e8tres de Rosas, nich\u00e9e dans la cala Montjoi, l&rsquo;une des criques les plus sauvages et pr\u00e9serv\u00e9es de la Costa Brava, la El Bulli Foundation est bien plus qu&rsquo;un simple mus\u00e9e. C&rsquo;est un lieu de p\u00e8lerinage pour les amateurs de <a href=\"https:\/\/www.rosesrentals.com\/que-manger-roses-gastronomie-catalane\/\">gastronomie<\/a> du monde entier, un endroit o\u00f9 l&rsquo;histoire de la haute cuisine se m\u00eale \u00e0 la beaut\u00e9 brute de la nature m\u00e9diterran\u00e9enne. Une excursion incontournable depuis nos <a href=\"https:\/\/www.rosesrentals.com\/nos-appartements\/\">appartements \u00e0 Canyelles Petites<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea63ea3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea63ea3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59041c0\" data-id=\"59041c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0010a8d elementor-widget elementor-widget-heading\" data-id=\"0010a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">El Bulli Foundation cala Monjoi : de la l\u00e9gende au mus\u00e9e<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca2c546 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca2c546\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f42f5d4\" data-id=\"f42f5d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-913e9f5 elementor-widget elementor-widget-text-editor\" data-id=\"913e9f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Avant de devenir la El Bulli Foundation \u00e0 cala Montjoi, ce site \u00e9tait le restaurant le plus c\u00e9l\u00e8bre du monde. De 1983 \u00e0 2011, le chef catalan Ferran Adri\u00e0 y a r\u00e9volutionn\u00e9 la gastronomie mondiale, inventant la cuisine mol\u00e9culaire et accumulant les distinctions les plus prestigieuses de la plan\u00e8te, dont cinq fois le titre de meilleur restaurant du monde selon le classement San Pellegrino. R\u00e9server une table \u00e0 El Bulli \u00e9tait devenu aussi difficile que d&rsquo;obtenir des billets pour les Jeux Olympiques : plus de deux millions de demandes par an pour seulement 8 000 couverts.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f5ac63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f5ac63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8957c21\" data-id=\"8957c21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d4ddbc elementor-widget elementor-widget-text-editor\" data-id=\"9d4ddbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">En 2011, Ferran Adri\u00e0 a ferm\u00e9 le restaurant pour le transformer en quelque chose d&rsquo;unique : un centre de cr\u00e9ativit\u00e9 culinaire et d&rsquo;archives gastronomiques, ouvert au public sous la forme d&rsquo;une exp\u00e9rience immersive. La Fondation El Bulli (ou elBulli1846) a ouvert ses portes en 2023 et propose aujourd&rsquo;hui une plong\u00e9e fascinante dans les coulisses de la r\u00e9volution gastronomique du XXe si\u00e8cle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffb1a01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffb1a01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aabab45\" data-id=\"aabab45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11b43f6 elementor-widget elementor-widget-heading\" data-id=\"11b43f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Qu'est-ce qu'elBulli1846 ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-657ff26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"657ff26\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec26d4a\" data-id=\"ec26d4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c6fa7c elementor-widget elementor-widget-text-editor\" data-id=\"7c6fa7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La visite d&rsquo;elBulli1846 est une exp\u00e9rience \u00e0 part enti\u00e8re, con\u00e7ue comme un parcours mus\u00e9al et sensoriel. On y d\u00e9couvre les archives compl\u00e8tes du restaurant, plus de 1 846 recettes (d&rsquo;o\u00f9 le nom), des milliers de photos, de vid\u00e9os, de carnets de notes et d&rsquo;objets issus des cuisines l\u00e9gendaires de Cala Montjoi.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Le parcours retrace l&rsquo;histoire d&rsquo;El Bulli depuis ses d\u00e9buts comme simple chiringuito de plage dans les ann\u00e9es 1960 jusqu&rsquo;\u00e0 son apog\u00e9e mondiale, en passant par les grandes \u00e9tapes de la r\u00e9volution cr\u00e9ative de Ferran Adri\u00e0. Des installations interactives permettent de comprendre les techniques de cuisine mol\u00e9culaire, les processus cr\u00e9atifs et les coulisses d&rsquo;un restaurant qui a chang\u00e9 la fa\u00e7on dont le monde per\u00e7oit la gastronomie.<\/p><p>La visite dure environ deux heures et est disponible en plusieurs langues, dont le fran\u00e7ais. La r\u00e9servation en ligne est indispensable. En effet les places partent vite, notamment en haute saison.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9e6110 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9e6110\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ee4b30\" data-id=\"1ee4b30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fbcad8 elementor-widget elementor-widget-heading\" data-id=\"8fbcad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aller \u00e0 la El Bulli Foundation cala Monjoi depuis nos appartements ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23010e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23010e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0437eb1\" data-id=\"0437eb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4113c81 elementor-widget elementor-widget-text-editor\" data-id=\"4113c81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Depuis nos <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/nos-appartements\/\">appartements de Canyelles Petites<\/a>, Cala Montjoi est accessible en voiture en moins de 15 minutes. Prenez la direction du Cap de Creus via l&rsquo;avenue Gran Via de Pau Casals, puis suivez les panneaux Cala Montjoi \/ Cala J\u00f2ncols. La route est sinueuse et \u00e9troite (pr\u00e9voyez suffisamment de temps).<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u26a0\ufe0f <strong>Important en haute saison<\/strong> : du 15 juillet au 31 ao\u00fbt, entre 10h30 et 16h30, l&rsquo;acc\u00e8s en voiture aux criques du parc naturel du Cap de Creus est interdit, sauf cas justifi\u00e9. Pr\u00e9voyez d&rsquo;arriver avant 10h30 ou apr\u00e8s 16h30 pour \u00e9viter les restrictions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f74eeba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f74eeba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c904a99\" data-id=\"c904a99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73bcfbb elementor-widget elementor-widget-heading\" data-id=\"73bcfbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prolonger l'exp\u00e9rience : d\u00e9jeuner face \u00e0 la mer<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf7b3df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf7b3df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0ea0ee\" data-id=\"c0ea0ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f690d87 elementor-widget elementor-widget-text-editor\" data-id=\"f690d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Une visite \u00e0 elBulli1846 se combine id\u00e9alement avec un d\u00e9jeuner dans l&rsquo;une des deux criques voisines.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1aa83d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1aa83d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e3217b\" data-id=\"5e3217b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c79e06 elementor-widget elementor-widget-heading\" data-id=\"3c79e06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Option 1 : Xiringuito de Cala Montjoi<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4776fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4776fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d57351\" data-id=\"8d57351\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3da67d8 elementor-widget elementor-widget-text-editor\" data-id=\"3da67d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Directement sur la <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/plages-roses-costa-brava\/\">plage de Cala Montjoi<\/a>, le Xiringuito propose une cuisine m\u00e9diterran\u00e9enne g\u00e9n\u00e9reuse labellis\u00e9e <em>Gastronomia d&rsquo;Origen<\/em> : produits locaux et frais du jour. Riz au homard, riz noir, fruits de mer, tapas et poissons grill\u00e9s servis face \u00e0 une eau turquoise d&rsquo;une clart\u00e9 exceptionnelle. Ambiance d\u00e9contract\u00e9e, familiale et authentiquement catalane.<\/p><ul><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udccd <strong>Xiringuito de Cala Montjoi<\/strong> Ctra. de la Roca s\/n, Cala Montjoi, 17480 Roses<\/li><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83c\udf10 <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.montjoi.com\">montjoi.com<\/a><\/li><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udcde +34 636 115 708<\/li><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udcb6 Budget : 20 \u00e0 50 \u20ac par personne selon formule<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6e1d61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6e1d61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad4d96f\" data-id=\"ad4d96f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26e87c8 elementor-widget elementor-widget-heading\" data-id=\"26e87c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Option 2 : Restaurant de Cala Pelosa<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-016039e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"016039e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36134f3\" data-id=\"36134f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5ed238 elementor-widget elementor-widget-text-editor\" data-id=\"c5ed238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Pour les amateurs de spots confidentiels, <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/plages-roses-costa-brava\/\">Cala Pelosa<\/a> est l&rsquo;alternative parfaite. Cette petite crique sauvage cache un restaurant discret nich\u00e9 sous les pins, presque invisible depuis la plage. Terrasse ombrag\u00e9e, atmosph\u00e8re intimiste, cuisine m\u00e9diterran\u00e9enne fra\u00eeche et simple servie face \u00e0 une mer cristalline. Id\u00e9al pour un d\u00e9jeuner en amoureux ou une pause familiale loin de toute agitation.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udccd <strong>Restaurant de Cala Pelosa<\/strong> Cala Pelosa, 17480 Roses<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83c\udf7d\ufe0f <a href=\"https:\/\/restaurantlapelosa.myrestoo.net\/es\/reservar?fb\" target=\"_blank\" rel=\"noopener\">R\u00e9server une table<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15c673a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15c673a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f8d6b6\" data-id=\"5f8d6b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ddc0d1 elementor-widget elementor-widget-heading\" data-id=\"8ddc0d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Infos pratiques elBulli1846<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe48170 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe48170\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fdc0393\" data-id=\"fdc0393\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4da31ab elementor-widget elementor-widget-text-editor\" data-id=\"4da31ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udccd <strong>Fondation El Bulli &#8211; elBulli1846\u00a0<\/strong>Cala Montjoi, 17480 Roses, Girona, Espagne<\/li><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83c\udf10 <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.elbulli1846.com\">elbulli1846.com<\/a><\/li><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udd50 Dur\u00e9e de visite : environ 2 heures<\/li><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83c\udf9f\ufe0f <a href=\"https:\/\/tickets.elbulli1846.com\/fr\/\" target=\"_blank\" rel=\"noopener\"><strong>R\u00e9servation en ligne indispensable<\/strong><\/a>\u00a0 places limit\u00e9es<\/li><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\ude97 Acc\u00e8s uniquement en voiture depuis Roses (15 min depuis Canyelles Petites)<\/li><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u26a0\ufe0f Acc\u00e8s restreint en voiture du 15 juillet au 31 ao\u00fbt entre 10h30 et 16h30<\/li><li class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udc68\u200d\ud83d\udc69\u200d\ud83d\udc67 Id\u00e9al pour : amateurs de gastronomie, curieux, familles avec enfants \u00e0 partir de 10 ans<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5cb160 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5cb160\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a134141\" data-id=\"a134141\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64bfc05 elementor-widget elementor-widget-heading\" data-id=\"64bfc05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A retenir<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba02ba8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba02ba8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c1cd2e\" data-id=\"5c1cd2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a66fd83 elementor-widget elementor-widget-text-editor\" data-id=\"a66fd83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>\u00c0 retenir<\/strong><\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La Fondation El Bulli est l&rsquo;une des visites les plus originales et les plus marquantes que la Costa Brava ait \u00e0 offrir. Depuis votre location de vacances dans un de nos <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/nos-appartements\/\">appartements \u00e0 Canyelles Petites<\/a>, comptez une demi-journ\u00e9e minimum ou une journ\u00e9e compl\u00e8te si vous ajoutez une baignade et un d\u00e9jeuner sur l&rsquo;une des criques voisines. Pour pr\u00e9parer votre s\u00e9jour, consultez notre <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/guide-vacances-roses\/\">guide complet des activit\u00e9s \u00e0 Roses<\/a> et notre article sur les <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/10-choses-a-faire-a-roses\/\">10 choses \u00e0 faire \u00e0 Roses en famille<\/a>.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><em>Une excursion \u00e0 ne manquer sous aucun pr\u00e9texte.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 quelques kilom\u00e8tres de Rosas, nich\u00e9e dans la cala Montjoi, l&rsquo;une des criques les plus sauvages et pr\u00e9serv\u00e9es de la Costa Brava, la El Bulli Foundation est bien plus qu&rsquo;un simple mus\u00e9e. C&rsquo;est un lieu de p\u00e8lerinage pour les amateurs de gastronomie du monde entier, un endroit o\u00f9 l&rsquo;histoire de la haute cuisine se m\u00eale [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3517,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-3494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-excursions-depuis-roses"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Bulli cala Monjoi | Roses Rentals<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez la Fondation El Bulli \u00e0 Cala Montjoi, \u00e0 15 minutes de Roses. Histoire, infos pratiques et adresses pour d\u00e9jeuner apr\u00e8s la visite\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosesrentals.com\/nl\/el-bulli-cala-montjoi\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Bulli Foundation \u00e0 Cala Montjoi - Visite et d\u00e9jeuner sur la Costa Brava\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez la Fondation El Bulli \u00e0 Cala Montjoi, \u00e0 15 minutes de Roses. Histoire, infos pratiques et adresses pour d\u00e9jeuner apr\u00e8s la visite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosesrentals.com\/nl\/el-bulli-cala-montjoi\/\" \/>\n<meta property=\"og:site_name\" content=\"Roses Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T09:49:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T14:20:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/3-ELBULLI1846-EXPOEXTERIOR-\u00aePepoSegura_1M3A9430.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Philippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/\",\"name\":\"El Bulli cala Monjoi | Roses Rentals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3-ELBULLI1846-EXPOEXTERIOR-\u00aePepoSegura_1M3A9430.jpg\",\"datePublished\":\"2026-04-17T09:49:12+00:00\",\"dateModified\":\"2026-05-12T14:20:56+00:00\",\"description\":\"D\u00e9couvrez la Fondation El Bulli \u00e0 Cala Montjoi, \u00e0 15 minutes de Roses. Histoire, infos pratiques et adresses pour d\u00e9jeuner apr\u00e8s la visite\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3-ELBULLI1846-EXPOEXTERIOR-\u00aePepoSegura_1M3A9430.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3-ELBULLI1846-EXPOEXTERIOR-\u00aePepoSegura_1M3A9430.jpg\",\"width\":1280,\"height\":515,\"caption\":\"el bulli foundation cala montjoi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rosesrentals.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Bulli Foundation \u00e0 Cala Montjoi &#8211; Visite et d\u00e9jeuner sur la Costa Brava\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"name\":\"rosesrentals.com\",\"description\":\"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rosesrentals.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\",\"name\":\"roses Rentals\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rosesrentals\",\"https:\\\/\\\/www.instagram.com\\\/rosesrentals\"],\"description\":\"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.\",\"telephone\":[],\"openingHoursSpecification\":[]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/el-bulli-cala-montjoi\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"width\":150,\"height\":150,\"caption\":\"roses Rentals\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Bulli cala Monjoi | Roses Verhuur","description":"Ontdek de El Bulli Foundation in Cala Montjoi, op 15 minuten van Roses. Geschiedenis, praktische informatie en adressen om te lunchen na je bezoek","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosesrentals.com\/nl\/el-bulli-cala-montjoi\/","og_locale":"nl_NL","og_type":"article","og_title":"El Bulli Foundation \u00e0 Cala Montjoi - Visite et d\u00e9jeuner sur la Costa Brava","og_description":"D\u00e9couvrez la Fondation El Bulli \u00e0 Cala Montjoi, \u00e0 15 minutes de Roses. Histoire, infos pratiques et adresses pour d\u00e9jeuner apr\u00e8s la visite","og_url":"https:\/\/www.rosesrentals.com\/nl\/el-bulli-cala-montjoi\/","og_site_name":"Roses Rentals","article_publisher":"https:\/\/www.facebook.com\/rosesrentals","article_author":"https:\/\/www.facebook.com\/rosesrentals","article_published_time":"2026-04-17T09:49:12+00:00","article_modified_time":"2026-05-12T14:20:56+00:00","og_image":[{"width":1280,"height":515,"url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/3-ELBULLI1846-EXPOEXTERIOR-\u00aePepoSegura_1M3A9430.jpg","type":"image\/jpeg"}],"author":"Philippe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/","url":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/","name":"El Bulli cala Monjoi | Roses Verhuur","isPartOf":{"@id":"https:\/\/www.rosesrentals.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/#primaryimage"},"image":{"@id":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/3-ELBULLI1846-EXPOEXTERIOR-\u00aePepoSegura_1M3A9430.jpg","datePublished":"2026-04-17T09:49:12+00:00","dateModified":"2026-05-12T14:20:56+00:00","description":"Ontdek de El Bulli Foundation in Cala Montjoi, op 15 minuten van Roses. Geschiedenis, praktische informatie en adressen om te lunchen na je bezoek","breadcrumb":{"@id":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/#primaryimage","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/3-ELBULLI1846-EXPOEXTERIOR-\u00aePepoSegura_1M3A9430.jpg","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/3-ELBULLI1846-EXPOEXTERIOR-\u00aePepoSegura_1M3A9430.jpg","width":1280,"height":515,"caption":"el bulli foundation cala montjoi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rosesrentals.com\/"},{"@type":"ListItem","position":2,"name":"El Bulli Foundation \u00e0 Cala Montjoi &#8211; Visite et d\u00e9jeuner sur la Costa Brava"}]},{"@type":"WebSite","@id":"https:\/\/www.rosesrentals.com\/#website","url":"https:\/\/www.rosesrentals.com\/","name":"rosesrentals.com","description":"Vakantieverblijf Roses Costa Brava | Appartementen met zeezicht - Roses Rentals","publisher":{"@id":"https:\/\/www.rosesrentals.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosesrentals.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":["Organization","Place"],"@id":"https:\/\/www.rosesrentals.com\/#organization","name":"Rozen Verhuur","url":"https:\/\/www.rosesrentals.com\/","logo":{"@id":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/rosesrentals","https:\/\/www.instagram.com\/rosesrentals"],"description":"Roses Rentals is een directe verhuurder van vakantiewoningen en biedt twee appartementen met zeezicht in Roses (Rosas), aan de Costa Brava in Cataloni\u00eb, Spanje. Gelegen in de residenti\u00eble wijk Canyelles Petites, op twee minuten loopafstand van het strand, bieden onze appartementen plaats aan maximaal 4 personen in een rustige en authentieke omgeving. Terrassen met zeezicht, parkeergelegenheid inbegrepen, zelfstandige check-in. Direct boeken zonder platformkosten, beste prijzen gegarandeerd. Ideaal voor een vakantie met familie of als koppel aan de Costa Brava.","telephone":[],"openingHoursSpecification":[]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.rosesrentals.com\/el-bulli-cala-montjoi\/#local-main-organization-logo","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","width":150,"height":150,"caption":"roses Rentals"}]}},"_links":{"self":[{"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/posts\/3494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/comments?post=3494"}],"version-history":[{"count":32,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/posts\/3494\/revisions"}],"predecessor-version":[{"id":4267,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/posts\/3494\/revisions\/4267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/media\/3517"}],"wp:attachment":[{"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/media?parent=3494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/categories?post=3494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/tags?post=3494"}],"curies":[{"name":"wordpress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}