{"id":89,"date":"2023-04-06T10:28:43","date_gmt":"2023-04-06T10:28:43","guid":{"rendered":"https:\/\/rosaslocation.com\/reservation\/"},"modified":"2026-05-17T07:10:18","modified_gmt":"2026-05-17T07:10:18","slug":"reservering","status":"publish","type":"page","link":"https:\/\/www.rosesrentals.com\/nl\/reservation\/","title":{"rendered":"Reservering"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"89\" class=\"elementor elementor-89\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5b7622 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5b7622\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-003e909\" data-id=\"003e909\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ba6f76 elementor-widget elementor-widget-heading\" data-id=\"6ba6f76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Appartements en location vacances \u00e0 Roses - R\u00e9servation directe<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b932109 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b932109\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1dc701c\" data-id=\"1dc701c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fac1a13 elementor-widget elementor-widget-text-editor\" data-id=\"fac1a13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Vous cherchez une r\u00e9servation de vacances \u00e0 Rosas en direct, sans frais de service ? Bienvenue sur la page de nos deux appartements de location \u00e0 Roses (Rosas), Costa Brava. Situ\u00e9s \u00e0 Canyelles Petites, l&rsquo;un des quartiers les plus pris\u00e9s et les plus calmes de <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/visitroses.cat\/fr\">Roses<\/a>, nos appartements sont \u00e0 100 m\u00e8tres de la plage, avec vue mer panoramique, terrasse et parking priv\u00e9 inclus. Que vous veniez en famille, en couple ou entre amis, vous trouverez ici deux logements soigneusement \u00e9quip\u00e9s et entretenus, g\u00e9r\u00e9s directement par leurs propri\u00e9taires Philippe et Olivier &#8211; deux Toulousains tomb\u00e9s amoureux de la Costa Brava. Pas d&rsquo;interm\u00e9diaire, pas d&rsquo;agence : vous \u00e9changez directement avec les propri\u00e9taires, du premier message jusqu&rsquo;au d\u00e9part. S\u00e9lectionnez vos dates ci-dessous pour v\u00e9rifier les disponibilit\u00e9s et r\u00e9server directement, <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/pourquoi-reserver-en-direct\/\">sans frais de service<\/a> contrairement aux grandes plateformes comme Airbnb ou Booking.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62951a06 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"62951a06\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f8e4170\" data-id=\"3f8e4170\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19ba6198 elementor-widget elementor-widget-html\" data-id=\"19ba6198\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe id=\"bookingengine\" style=\"display: block;\" src=\"https:\/\/app.superhote.com\/#\/get-available-rentals\/BBMHpV5CartLvSt1TZV228B6n\" width=\"100%\" height=\"5500\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe>\r\n<script>\r\nvar webKey = \"BBMHpV5CartLvSt1TZV228B6n\";\r\nvar url = new URL(window.location.href);\r\nvar appart = url.searchParams.get(\"appart\");\r\nvar checkin = url.searchParams.get(\"checkin\");\r\nvar checkout = url.searchParams.get(\"checkout\");\r\nvar adults = url.searchParams.get(\"adults\");\r\nvar children = url.searchParams.get(\"children\");\r\nvar lang = url.searchParams.get(\"lang\");\r\nif(lang == null) {\r\n    var pathLang = window.location.pathname.split('\/')[1];\r\n    var validLangs = ['fr','en','de','es','nl','ca','it'];\r\n    lang = validLangs.includes(pathLang) ? pathLang : 'fr';\r\n}\r\nif(appart == null) {\r\n    var iframeUrl = \"https:\/\/app.superhote.com\/#\/get-available-rentals\/\"+webKey+\"?lang=\" + lang;\r\n    if(checkin != null) iframeUrl += \"&startDate=\" + checkin + \"&endDate=\" + checkout + \"&adultsNumber=\" + adults + \"&childrenNumber=\" + children;\r\n    document.getElementById('bookingengine').src = iframeUrl;\r\n} else {\r\n    var iframeUrl = \"https:\/\/app.superhote.com\/#\/rental\/\" + appart + \"?lang=\" + lang;\r\n    document.getElementById('bookingengine').src = iframeUrl;\r\n}\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f10403 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f10403\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f147910\" data-id=\"f147910\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9be30f elementor-widget elementor-widget-text-editor\" data-id=\"f9be30f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Pour une r\u00e9servation de vacances \u00e0 Rosas au meilleur prix, vous \u00eates au bon endroit. Vous h\u00e9sitez encore ? Consultez les <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/avis-reviews\/\">avis de nos voyageurs<\/a> pour vous faire une id\u00e9e pr\u00e9cise de ce qui vous attend, ou parcourez notre <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/guide-vacances-roses\/\">guide de Roses<\/a> pour pr\u00e9parer votre s\u00e9jour : <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/\">plages<\/a>, <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/dix-choses-a-faire-a-roses\/\">activit\u00e9s en famille<\/a>, <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/restaurants-canyelles-petites-roses\/\">restaurants<\/a>, <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/comment-venir-a-roses\/\">comment venir depuis la France ou Barcelone<\/a>\u2026 Tout ce qu&rsquo;il faut savoir pour arriver sereinement et profiter de chaque journ\u00e9e. La baie de Roses fait partie du club des <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.world-bays.com\/fr\/\">plus belles baies du monde<\/a> &#8211; une reconnaissance internationale qui t\u00e9moigne de l&rsquo;exceptionnelle qualit\u00e9 de ses paysages maritimes et de son environnement naturel pr\u00e9serv\u00e9. R\u00e9servez directement chez nous et profitez du meilleur prix garanti, d&rsquo;un contact humain d\u00e8s le premier message, et d&rsquo;un check-in autonome \u00e0 toute heure gr\u00e2ce \u00e0 notre bo\u00eete \u00e0 cl\u00e9s s\u00e9curis\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Appartements en location vacances \u00e0 Roses &#8211; R\u00e9servation directe Vous cherchez une r\u00e9servation de vacances \u00e0 Rosas en direct, sans frais de service ? Bienvenue sur la page de nos deux appartements de location \u00e0 Roses (Rosas), Costa Brava. Situ\u00e9s \u00e0 Canyelles Petites, l&rsquo;un des quartiers les plus pris\u00e9s et les plus calmes de Roses, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-89","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>R\u00e9servation vacances Roses | Roses Rentals<\/title>\n<meta name=\"description\" content=\"R\u00e9servation vacances Rosas en direct - 2 appartements vue mer \u00e0 Roses, Costa Brava. Sans frais de service, parking priv\u00e9, plage \u00e0 100m.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosesrentals.com\/nl\/reservering\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9servation\" \/>\n<meta property=\"og:description\" content=\"R\u00e9servation vacances Rosas en direct - 2 appartements vue mer \u00e0 Roses, Costa Brava. Sans frais de service, parking priv\u00e9, plage \u00e0 100m.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosesrentals.com\/nl\/reservering\/\" \/>\n<meta property=\"og:site_name\" content=\"Roses Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-17T07:10:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/reservation\\\/\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/reservation\\\/\",\"name\":\"R\u00e9servation vacances Roses | Roses Rentals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\"},\"datePublished\":\"2023-04-06T10:28:43+00:00\",\"dateModified\":\"2026-05-17T07:10:18+00:00\",\"description\":\"R\u00e9servation vacances Rosas en direct - 2 appartements vue mer \u00e0 Roses, Costa Brava. Sans frais de service, parking priv\u00e9, plage \u00e0 100m.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/reservation\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rosesrentals.com\\\/reservation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/reservation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rosesrentals.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9servation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"name\":\"rosesrentals.com\",\"description\":\"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rosesrentals.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\",\"name\":\"roses Rentals\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/reservation\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/reservation\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rosesrentals\",\"https:\\\/\\\/www.instagram.com\\\/rosesrentals\"],\"description\":\"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.\",\"telephone\":[],\"openingHoursSpecification\":[]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/reservation\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"width\":150,\"height\":150,\"caption\":\"roses Rentals\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vakantie Reserveringen Rozen | Rozen Verhuur","description":"Boekingsvakantie Rosas direct - 2 appartementen met zeezicht in Roses, Costa Brava. Geen servicekosten, priv\u00e9parkeergelegenheid, strand op 100m.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosesrentals.com\/nl\/reservering\/","og_locale":"nl_NL","og_type":"article","og_title":"R\u00e9servation","og_description":"R\u00e9servation vacances Rosas en direct - 2 appartements vue mer \u00e0 Roses, Costa Brava. Sans frais de service, parking priv\u00e9, plage \u00e0 100m.","og_url":"https:\/\/www.rosesrentals.com\/nl\/reservering\/","og_site_name":"Roses Rentals","article_publisher":"https:\/\/www.facebook.com\/rosesrentals","article_modified_time":"2026-05-17T07:10:18+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rosesrentals.com\/reservation\/","url":"https:\/\/www.rosesrentals.com\/reservation\/","name":"Vakantie Reserveringen Rozen | Rozen Verhuur","isPartOf":{"@id":"https:\/\/www.rosesrentals.com\/#website"},"datePublished":"2023-04-06T10:28:43+00:00","dateModified":"2026-05-17T07:10:18+00:00","description":"Boekingsvakantie Rosas direct - 2 appartementen met zeezicht in Roses, Costa Brava. Geen servicekosten, priv\u00e9parkeergelegenheid, strand op 100m.","breadcrumb":{"@id":"https:\/\/www.rosesrentals.com\/reservation\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosesrentals.com\/reservation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosesrentals.com\/reservation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rosesrentals.com\/"},{"@type":"ListItem","position":2,"name":"R\u00e9servation"}]},{"@type":"WebSite","@id":"https:\/\/www.rosesrentals.com\/#website","url":"https:\/\/www.rosesrentals.com\/","name":"rosesrentals.com","description":"Vakantieverblijf Roses Costa Brava | Appartementen met zeezicht - Roses Rentals","publisher":{"@id":"https:\/\/www.rosesrentals.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosesrentals.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":["Organization","Place"],"@id":"https:\/\/www.rosesrentals.com\/#organization","name":"Rozen Verhuur","url":"https:\/\/www.rosesrentals.com\/","logo":{"@id":"https:\/\/www.rosesrentals.com\/reservation\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.rosesrentals.com\/reservation\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/rosesrentals","https:\/\/www.instagram.com\/rosesrentals"],"description":"Roses Rentals is een directe verhuurder van vakantiewoningen en biedt twee appartementen met zeezicht in Roses (Rosas), aan de Costa Brava in Cataloni\u00eb, Spanje. Gelegen in de residenti\u00eble wijk Canyelles Petites, op twee minuten loopafstand van het strand, bieden onze appartementen plaats aan maximaal 4 personen in een rustige en authentieke omgeving. Terrassen met zeezicht, parkeergelegenheid inbegrepen, zelfstandige check-in. Direct boeken zonder platformkosten, beste prijzen gegarandeerd. Ideaal voor een vakantie met familie of als koppel aan de Costa Brava.","telephone":[],"openingHoursSpecification":[]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.rosesrentals.com\/reservation\/#local-main-organization-logo","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","width":150,"height":150,"caption":"roses Rentals"}]}},"_links":{"self":[{"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/pages\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":124,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/pages\/89\/revisions"}],"predecessor-version":[{"id":4653,"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/pages\/89\/revisions\/4653"}],"wp:attachment":[{"href":"https:\/\/www.rosesrentals.com\/nl\/wp-json\/wp\/v2\/media?parent=89"}],"curies":[{"name":"wordpress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}