{"id":1903,"date":"2026-02-28T11:09:19","date_gmt":"2026-02-28T11:09:19","guid":{"rendered":"https:\/\/www.rosesrentals.com\/?p=1903"},"modified":"2026-05-12T14:19:44","modified_gmt":"2026-05-12T14:19:44","slug":"spiagge-rosa-costa-brava","status":"publish","type":"post","link":"https:\/\/www.rosesrentals.com\/it\/plages-roses-costa-brava\/","title":{"rendered":"Le pi\u00f9 belle spiagge di Roses e della Costa Brava"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1903\" class=\"elementor elementor-1903\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dbd17df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbd17df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-efc1b7b\" data-id=\"efc1b7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9833e15 elementor-widget elementor-widget-text-editor\" data-id=\"9833e15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Rosas est l&rsquo;une des <a href=\"https:\/\/www.rosesrentals.com\/meilleure-periode-roses-costa-brava\/\">destinations baln\u00e9aires<\/a> les plus pris\u00e9es d&rsquo;Espagne, et pour cause : la commune offre une diversit\u00e9 de <a href=\"\/vacances-ete-roses-costa-brava\/\">plages et de criques<\/a> remarquable, allant des grandes \u00e9tendues de sable familiales aux criques sauvages nich\u00e9es dans le parc naturel du Cap de Creus. Voici notre guide complet pour choisir la plage qui vous correspond.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea63ea3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea63ea3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59041c0\" data-id=\"59041c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0010a8d elementor-widget elementor-widget-heading\" data-id=\"0010a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Les plages urbaines de Roses : id\u00e9ales en famille<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-631d703 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"631d703\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cb55fb\" data-id=\"2cb55fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9900ae5 elementor-widget elementor-widget-heading\" data-id=\"9900ae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udfd6\ufe0f La Plage de Santa Margarida<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca2c546 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca2c546\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f42f5d4\" data-id=\"f42f5d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-913e9f5 elementor-widget elementor-widget-text-editor\" data-id=\"913e9f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Situ\u00e9e dans l&rsquo;urbanisation du m\u00eame nom, la plage de Santa Margarida se distingue par son sable fin et dor\u00e9 et ses eaux peu profondes, ce qui en fait une plage tr\u00e8s appr\u00e9ci\u00e9e des familles.\u00a0Elle dispose de toutes les infrastructures : parking, restaurants, promenade maritime et activit\u00e9s nautiques.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Id\u00e9al pour :<\/strong> les familles avec jeunes enfants. \u26a0\ufe0f \u00c0 noter : expos\u00e9e \u00e0 la tramontane, le vent du nord caract\u00e9ristique de la r\u00e9gion.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa3e714 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa3e714\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3efd8e\" data-id=\"e3efd8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac4140f elementor-widget elementor-widget-heading\" data-id=\"ac4140f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udfd6\ufe0f La Plage de Salatar<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f5ac63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f5ac63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8957c21\" data-id=\"8957c21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d4ddbc elementor-widget elementor-widget-text-editor\" data-id=\"9d4ddbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La plage de Salatar s&rsquo;\u00e9tend sur environ 500 m\u00e8tres de long et 35 m\u00e8tres de large, avec du sable fin et des eaux peu profondes et claires. Le long de la plage court le Paseo Mar\u00edtimo, id\u00e9al pour la marche ou le v\u00e9lo.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Id\u00e9al pour :<\/strong> les balades en bord de mer, le beach-volley.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffb1a01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffb1a01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aabab45\" data-id=\"aabab45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11b43f6 elementor-widget elementor-widget-heading\" data-id=\"11b43f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udfd6\ufe0f La Plage Nova (centre-ville)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d4b947 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d4b947\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2673763\" data-id=\"2673763\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d0d53e elementor-widget elementor-widget-text-editor\" data-id=\"2d0d53e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La Plage Nova s&rsquo;\u00e9tend du brise-lames de Riera Ginjolers au Rec d&rsquo;en Forquilla, sur environ 450 m\u00e8tres de long, avec du sable fin et des eaux claires et peu profondes. C&rsquo;est la plage la plus accessible depuis le centre de Roses, \u00e0 deux pas des commerces et restaurants.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Id\u00e9al pour :<\/strong> ceux qui souhaitent rester proches de l&rsquo;animation du centre-ville.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c476453 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c476453\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-505986b\" data-id=\"505986b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b380e6c elementor-widget elementor-widget-heading\" data-id=\"b380e6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Les criques semi-sauvages : le meilleur de deux mondes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6382d52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6382d52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e868577\" data-id=\"e868577\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9deb0a9 elementor-widget elementor-widget-heading\" data-id=\"9deb0a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udf0a Canyelles Petites<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-657ff26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"657ff26\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec26d4a\" data-id=\"ec26d4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c6fa7c elementor-widget elementor-widget-text-editor\" data-id=\"7c6fa7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Situ\u00e9e \u00e0 environ 3 km du centre de Roses, <a href=\"https:\/\/visitroses.cat\/fr\/decouvrir\/plages-et-criques\/plage-canyelles-petites.html\" target=\"_blank\" rel=\"noopener\">Canyelles Petites<\/a> est une plage de sable fin et dor\u00e9 aux eaux transparentes, d&rsquo;environ 350 m\u00e8tres de long. Elle est particuli\u00e8rement appr\u00e9ci\u00e9e des baigneurs car prot\u00e9g\u00e9e du vent du nord.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Id\u00e9al pour :<\/strong> le <a href=\"https:\/\/www.rosesrentals.com\/activites-nautiques-roses-costa-brava\/\">snorkeling<\/a>, la baignade calme, les familles qui recherchent un peu de tranquillit\u00e9.<\/p><p>Notre appartement <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/appartement-vue-mer-roses-terrasse\/\">vue mer avec terrasse<\/a> et notre <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/\">appartement r\u00e9nov\u00e9<\/a> sont tous les deux situ\u00e9s \u00e0 100 m\u00e8tres de la plage de Canyelles Petites.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68f63ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68f63ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db07d65\" data-id=\"db07d65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96923f8 elementor-widget elementor-widget-heading\" data-id=\"96923f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udf0a Plage de l'Almadrava (Canyelles Grans)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23010e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23010e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0437eb1\" data-id=\"0437eb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4113c81 elementor-widget elementor-widget-text-editor\" data-id=\"4113c81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u00c0 environ 5 km de Roses, l&rsquo;Almadrava est une grande plage de sable fin aux eaux d&rsquo;un bleu intense, abrit\u00e9e de la tramontane. Elle dispose de plusieurs bars de plage et de tous les services c\u00f4tiers, avec possibilit\u00e9 de louer des kayaks.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Id\u00e9al pour :<\/strong> les amateurs de sports nautiques, les s\u00e9jours prolong\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9e6110 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9e6110\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ee4b30\" data-id=\"1ee4b30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fbcad8 elementor-widget elementor-widget-heading\" data-id=\"8fbcad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Les criques sauvages du Cap de Creus : pour les aventuriers<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f74eeba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f74eeba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c904a99\" data-id=\"c904a99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73bcfbb elementor-widget elementor-widget-heading\" data-id=\"73bcfbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udfdd\ufe0f Cala Montjoi<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf7b3df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf7b3df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0ea0ee\" data-id=\"c0ea0ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f690d87 elementor-widget elementor-widget-text-editor\" data-id=\"f690d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cala Montjoi est une crique superbe, compl\u00e8tement isol\u00e9e dans le parc naturel du Cap de Creus, \u00e0 quelques kilom\u00e8tres de Roses. Expos\u00e9e au sud et prot\u00e9g\u00e9e des vents, c&rsquo;est un endroit idyllique pour profiter de la plage. Elle est \u00e9galement connue mondialement pour avoir accueilli l&rsquo;ancien restaurant <a href=\"https:\/\/elbullifoundation.com\/elbulli1846\/en\/what-is-elbulli1846\/\" target=\"_blank\" rel=\"noopener\">El Bulli<\/a> de Ferran Adri\u00e0.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Id\u00e9al pour :<\/strong> les couples, les amateurs de plong\u00e9e sous-marine, les gastronomes curieux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1aa83d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1aa83d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e3217b\" data-id=\"5e3217b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c79e06 elementor-widget elementor-widget-heading\" data-id=\"3c79e06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udfdd\ufe0f Cala J\u00f2ncols<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4776fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4776fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d57351\" data-id=\"8d57351\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3da67d8 elementor-widget elementor-widget-text-editor\" data-id=\"3da67d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cala J\u00f2ncols est une crique vierge au paysage sauvage et aux falaises abruptes, situ\u00e9e \u00e0 18 km de Roses. Accessible par la route c\u00f4ti\u00e8re, ses fonds marins en font une zone id\u00e9ale pour la plong\u00e9e sous-marine.<\/p><p>On y trouve le premier h\u00f4tel de la Costa Brava \u00e0 obtenir le label Biosphere. Le <a href=\"https:\/\/www.calajoncols.com\/fr\/la-gastronomie\/\" target=\"_blank\" rel=\"noopener\">restaurant<\/a> est labellis\u00e9 G&rsquo;O (Gastronomie d&rsquo;origine), car toute la cuisine est pr\u00e9par\u00e9e avec des produits frais du jour : les poissons proviennent de la Guilde des P\u00eacheurs de Roses, les l\u00e9gumes des vergers de l&rsquo;h\u00f4tel, l&rsquo;huile de leurs oliviers, et le vin, bien s\u00fbr, de leurs vignes. Produits de saison et de qualit\u00e9.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Id\u00e9al pour :<\/strong>\u00a0la plong\u00e9e, les randonneurs, ceux qui recherchent l\u2019isolement total.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6e1d61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6e1d61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad4d96f\" data-id=\"ad4d96f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26e87c8 elementor-widget elementor-widget-heading\" data-id=\"26e87c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udfdd\ufe0f Cala Murtra<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-016039e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"016039e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36134f3\" data-id=\"36134f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5ed238 elementor-widget elementor-widget-text-editor\" data-id=\"c5ed238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Une des criques les plus secr\u00e8tes et les plus sauvages de la zone. Cala Murtra est une petite crique solitaire au paysage sauvage, situ\u00e9e \u00e0 environ 10 km de Roses. On y acc\u00e8de \u00e0 pied depuis la route de Montjoi (environ 20 minutes de marche), ce qui garantit une fr\u00e9quentation tr\u00e8s limit\u00e9e.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Id\u00e9al pour :<\/strong> les amateurs de nature vierge, la baignade en solitaire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15c673a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15c673a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f8d6b6\" data-id=\"5f8d6b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ddc0d1 elementor-widget elementor-widget-heading\" data-id=\"8ddc0d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udfd6\ufe0f Cala Pelosa, la crique secr\u00e8te des initi\u00e9s<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe48170 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe48170\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fdc0393\" data-id=\"fdc0393\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4da31ab elementor-widget elementor-widget-text-editor\" data-id=\"4da31ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u00c0 quelques minutes de Canyelles Petites, Cala Pelosa est l&rsquo;une de ces criques que l&rsquo;on garde jalousement pour soi&#8230;<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Loin de l&rsquo;agitation des grandes plages de Roses, on y trouve une tranquillit\u00e9 rare, les pieds dans une eau cristalline \u00e0 l&rsquo;abri du vent. Mais Cala Pelosa cache un autre tr\u00e9sor, bien moins connu encore : un restaurant discret, presque invisible, nich\u00e9 sous les pins et les arbres qui surplombent la crique. Terrasse ombrag\u00e9e, atmosph\u00e8re d\u00e9contract\u00e9e, cuisine catalane simple et fra\u00eeche. C&rsquo;est exactement le genre d&rsquo;adresse que l&rsquo;on d\u00e9couvre par hasard et que l&rsquo;on ne partage qu&rsquo;aux amis de confiance. <a href=\"\/que-manger-roses-gastronomie-catalane\/\">Poissons grill\u00e9s, salades m\u00e9diterran\u00e9ennes et boissons fra\u00eeches<\/a> servis face \u00e0 la mer, les pieds presque dans le sable : difficile de faire mieux pour une pause d\u00e9jeuner en pleine nature. Une adresse confidentielle qui, \u00e0 elle seule, justifie le d\u00e9tour.<\/p><p><strong>Id\u00e9al pour :<\/strong> les amoureux de nature et les \u00e9picuriens en qu\u00eate d&rsquo;authenticit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5cb160 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5cb160\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a134141\" data-id=\"a134141\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64bfc05 elementor-widget elementor-widget-heading\" data-id=\"64bfc05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Au-del\u00e0 de Roses : les incontournables de la Costa Brava<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a87631 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a87631\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6710c10\" data-id=\"6710c10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3211511 elementor-widget elementor-widget-heading\" data-id=\"3211511\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udf1f Cadaqu\u00e9s &amp; Cap de Creus<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba02ba8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba02ba8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c1cd2e\" data-id=\"5c1cd2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a66fd83 elementor-widget elementor-widget-text-editor\" data-id=\"a66fd83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le <a href=\"https:\/\/parcsnaturals.gencat.cat\/ca\/xarxa-de-parcs\/fitxes-dels-parcs\/fitxa-cap-de-creus\/\" target=\"_blank\" rel=\"noopener\">Cap de Creus<\/a> abrite une multitude de criques sauvages parmi les plus belles de la Costa Brava, dont la plage de Sa Sabolla, accessible \u00e0 pied par le chemin de ronde ou par la mer. Le village de Cadaqu\u00e9s, \u00e0 30 minutes de Roses en voiture, est un passage oblig\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d28123a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d28123a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a02f228\" data-id=\"a02f228\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-138f660 elementor-widget elementor-widget-heading\" data-id=\"138f660\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\ud83c\udf1f Empuriabrava<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d519e3e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d519e3e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-411137d\" data-id=\"411137d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee49afd elementor-widget elementor-widget-text-editor\" data-id=\"ee49afd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"\/empuriabrava-depuis-roses-marina-canaux\/\">La plage d&rsquo;Empuriabrava<\/a> s&rsquo;\u00e9tend sur plus d&rsquo;1,5 kilom\u00e8tre avec son drapeau bleu, offrant une belle vue sur la baie de Roses et le parc naturel du Cap de Creus. C&rsquo;est aussi l&rsquo;occasion de d\u00e9couvrir la c\u00e9l\u00e8bre \u00ab\u00a0Venise espagnole\u00a0\u00bb et ses 30 kilom\u00e8tres de canaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1261ed1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1261ed1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf59934\" data-id=\"bf59934\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31e7107 elementor-widget elementor-widget-heading\" data-id=\"31e7107\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Notre tableau r\u00e9capitulatif<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-519e877 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"519e877\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b1835c0\" data-id=\"b1835c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a9e2bb elementor-widget elementor-widget-text-editor\" data-id=\"8a9e2bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\">\u00a0<\/h2><div class=\"overflow-x-auto w-full px-2 mb-6\"><table class=\"min-w-full border-collapse text-sm leading-[1.7] whitespace-normal\"><thead class=\"text-left\"><tr><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Plage<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Distance de Roses<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Ambiance<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Id\u00e9al pour<\/th><\/tr><\/thead><tbody><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Santa Margarida<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">2 km<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Familiale anim\u00e9e<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Familles, enfants<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Plage Nova<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Centre-ville<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Urbaine<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Commodit\u00e9s, animation<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Canyelles Petites<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">3 km<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Semi-sauvage<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Snorkeling, calme<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Almadrava<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">5 km<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Nature &amp; services<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Sports nautiques<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Cala Montjoi<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">12 km<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Sauvage<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Plong\u00e9e, couples<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Cala J\u00f2ncols<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">18 km<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Isol\u00e9e<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Randonn\u00e9e, plong\u00e9e<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Cala Murtra<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">10 km<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Tr\u00e8s sauvage<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Solitude, nature<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb136fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb136fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-992c432\" data-id=\"992c432\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46f3aac elementor-widget elementor-widget-heading\" data-id=\"46f3aac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Conseils pratiques<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa55a3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa55a3b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-02db10c\" data-id=\"02db10c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38abd36 elementor-widget elementor-widget-text-editor\" data-id=\"38abd36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>\ud83d\ude97 Se d\u00e9placer :<\/strong> Pour les criques sauvages (Montjoi, J\u00f2ncols, Murtra), la voiture est indispensable. Pr\u00e9voyez de partir t\u00f4t le matin en juillet-ao\u00fbt, les parkings se remplissent vite.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>\ud83d\udc5f Le chemin de ronde :<\/strong> Le sentier littoral GR-92 relie la plupart des plages et criques de Roses \u00e0 pied. C&rsquo;est une fa\u00e7on magnifique de les d\u00e9couvrir progressivement.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>\ud83e\udd3f Snorkeling :<\/strong> Les meilleures conditions se trouvent \u00e0 Canyelles Petites, Cala Montjoi et Cala J\u00f2ncols, o\u00f9 la transparence de l&rsquo;eau est remarquable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f56a79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f56a79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e244d1\" data-id=\"5e244d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-146cac0 elementor-widget elementor-widget-heading\" data-id=\"146cac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Profitez des plages de Roses depuis nos appartements<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71ed68d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71ed68d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70906a9\" data-id=\"70906a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6af7d8c elementor-widget elementor-widget-text-editor\" data-id=\"6af7d8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos appartements sont situ\u00e9s \u00e0 <strong>100 m\u00e8tres de la plage<\/strong>, avec vue mer. En r\u00e9servant votre location de vacances \u00e0 Rosas directement chez nous, vous \u00e9conomisez les frais de service des grandes plateformes tout en b\u00e9n\u00e9ficiant d&rsquo;un accueil personnalis\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rosas est l&rsquo;une des destinations baln\u00e9aires les plus pris\u00e9es d&rsquo;Espagne, et pour cause : la commune offre une diversit\u00e9 de plages et de criques remarquable, allant des grandes \u00e9tendues de sable familiales aux criques sauvages nich\u00e9es dans le parc naturel du Cap de Creus. Voici notre guide complet pour choisir la plage qui vous correspond. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites-decouvertes-locales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Plages de Roses Costa Brava | Roses Rentals<\/title>\n<meta name=\"description\" content=\"Santa Margarida, Canyelles Petites, criques sauvages du Cap de Creus\u2026 D\u00e9couvrez les plus belles plages de Roses et comment y acc\u00e9der.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosesrentals.com\/it\/spiagge-rosa-costa-brava\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les plus belles plages de Roses et de la Costa Brava\" \/>\n<meta property=\"og:description\" content=\"Santa Margarida, Canyelles Petites, criques sauvages du Cap de Creus\u2026 D\u00e9couvrez les plus belles plages de Roses et comment y acc\u00e9der.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosesrentals.com\/it\/spiagge-rosa-costa-brava\/\" \/>\n<meta property=\"og:site_name\" content=\"Roses Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-28T11:09:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T14:19:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/02\/cala-rostella-roses.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Philippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/\",\"name\":\"Plages de Roses Costa Brava | Roses Rentals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cala-rostella-roses.jpg\",\"datePublished\":\"2026-02-28T11:09:19+00:00\",\"dateModified\":\"2026-05-12T14:19:44+00:00\",\"description\":\"Santa Margarida, Canyelles Petites, criques sauvages du Cap de Creus\u2026 D\u00e9couvrez les plus belles plages de Roses et comment y acc\u00e9der.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cala-rostella-roses.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cala-rostella-roses.jpg\",\"width\":1920,\"height\":1100,\"caption\":\"plages Roses Costa Brava\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rosesrentals.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les plus belles plages de Roses et de la Costa Brava\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"name\":\"rosesrentals.com\",\"description\":\"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rosesrentals.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\",\"name\":\"roses Rentals\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rosesrentals\",\"https:\\\/\\\/www.instagram.com\\\/rosesrentals\"],\"description\":\"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.\",\"telephone\":[],\"openingHoursSpecification\":[]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/plages-roses-costa-brava\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"width\":150,\"height\":150,\"caption\":\"roses Rentals\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Spiagge di Roses Costa Brava | Affitti Roses","description":"Santa Margarida, Canyelles Petites, le calette selvagge di Cap de Creus\u2026 Scopri le spiagge pi\u00f9 belle di Roses e come raggiungerle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosesrentals.com\/it\/spiagge-rosa-costa-brava\/","og_locale":"it_IT","og_type":"article","og_title":"Les plus belles plages de Roses et de la Costa Brava","og_description":"Santa Margarida, Canyelles Petites, criques sauvages du Cap de Creus\u2026 D\u00e9couvrez les plus belles plages de Roses et comment y acc\u00e9der.","og_url":"https:\/\/www.rosesrentals.com\/it\/spiagge-rosa-costa-brava\/","og_site_name":"Roses Rentals","article_publisher":"https:\/\/www.facebook.com\/rosesrentals","article_author":"https:\/\/www.facebook.com\/rosesrentals","article_published_time":"2026-02-28T11:09:19+00:00","article_modified_time":"2026-05-12T14:19:44+00:00","og_image":[{"width":1920,"height":1100,"url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/02\/cala-rostella-roses.jpg","type":"image\/jpeg"}],"author":"Philippe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/","url":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/","name":"Spiagge di Roses Costa Brava | Affitti Roses","isPartOf":{"@id":"https:\/\/www.rosesrentals.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/#primaryimage"},"image":{"@id":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/02\/cala-rostella-roses.jpg","datePublished":"2026-02-28T11:09:19+00:00","dateModified":"2026-05-12T14:19:44+00:00","description":"Santa Margarida, Canyelles Petites, le calette selvagge di Cap de Creus\u2026 Scopri le spiagge pi\u00f9 belle di Roses e come raggiungerle.","breadcrumb":{"@id":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/#primaryimage","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/02\/cala-rostella-roses.jpg","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/02\/cala-rostella-roses.jpg","width":1920,"height":1100,"caption":"plages Roses Costa Brava"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rosesrentals.com\/"},{"@type":"ListItem","position":2,"name":"Les plus belles plages de Roses et de la Costa Brava"}]},{"@type":"WebSite","@id":"https:\/\/www.rosesrentals.com\/#website","url":"https:\/\/www.rosesrentals.com\/","name":"rosesrentals.com","description":"Affitto vacanze Roses Costa Brava | Appartamenti vista mare - Roses Rentals","publisher":{"@id":"https:\/\/www.rosesrentals.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosesrentals.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.rosesrentals.com\/#organization","name":"Noleggio rose","url":"https:\/\/www.rosesrentals.com\/","logo":{"@id":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/rosesrentals","https:\/\/www.instagram.com\/rosesrentals"],"description":"Roses Rentals \u00e8 un affitto vacanze diretto che offre due appartamenti con vista mare a Roses, sulla Costa Brava in Catalogna, Spagna. Situati nel quartiere residenziale di Canyelles Petites, a due minuti a piedi dalla spiaggia, i nostri appartamenti possono ospitare fino a 4 persone in un ambiente tranquillo e autentico. Terrazze con vista mare, parcheggio incluso, check-in autonomo. Prenotazione diretta senza commissioni di piattaforma, migliori prezzi garantiti. Ideale per vacanze in famiglia o di coppia sulla Costa Brava.","telephone":[],"openingHoursSpecification":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rosesrentals.com\/plages-roses-costa-brava\/#local-main-organization-logo","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","width":150,"height":150,"caption":"roses Rentals"}]}},"_links":{"self":[{"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/posts\/1903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/comments?post=1903"}],"version-history":[{"count":77,"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/posts\/1903\/revisions"}],"predecessor-version":[{"id":4261,"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/posts\/1903\/revisions\/4261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/media\/2989"}],"wp:attachment":[{"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/media?parent=1903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/categories?post=1903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosesrentals.com\/it\/wp-json\/wp\/v2\/tags?post=1903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}