{"id":92,"date":"2023-04-06T10:28:43","date_gmt":"2023-04-06T10:28:43","guid":{"rendered":"https:\/\/rosaslocation.com\/accueil\/"},"modified":"2026-05-14T15:28:19","modified_gmt":"2026-05-14T15:28:19","slug":"location-vacances-roses","status":"publish","type":"page","link":"https:\/\/www.rosesrentals.com\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"92\" class=\"elementor elementor-92\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-637057dd elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"637057dd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53efdfbf\" data-id=\"53efdfbf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25674ce animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"25674ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Vacances sur la Costa Brava<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2df212a animated-slow elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"2df212a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1db3bd7 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1db3bd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Appartements vue mer \u00e0 Roses, \u00e0 100 m\u00e8tres de la plage<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ceacca6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ceacca6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-290916c\" data-id=\"290916c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d40657e elementor-widget elementor-widget-spacer\" data-id=\"d40657e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9d3057 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9d3057\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d98888d\" data-id=\"d98888d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-306a67b elementor-widget elementor-widget-heading\" data-id=\"306a67b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Bienvenue chez Roses Rentals, votre location de vacances \u00e0 Rosas<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40676ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40676ff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5200e8\" data-id=\"c5200e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccbd9c0 elementor-widget elementor-widget-text-editor\" data-id=\"ccbd9c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Bienvenue chez Roses Rentals, votre adresse pour une location de vacances \u00e0 <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/visitroses.cat\/\" target=\"_blank\" rel=\"noopener\">Roses<\/a> inoubliable, en Espagne. Nos appartements sont id\u00e9alement situ\u00e9s \u00e0 deux pas de la mer, au c\u0153ur de Roses (Rosas) l&rsquo;une des plus belles stations baln\u00e9aires de la <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/costabrava.org\/\" target=\"_blank\" rel=\"noopener\">Costa Brava<\/a>. C&rsquo;est pourquoi Roses s\u00e9duit chaque ann\u00e9e des milliers de voyageurs gr\u00e2ce \u00e0 ses longues plages de sable fin, ses criques sauvages et son atmosph\u00e8re m\u00e9diterran\u00e9enne unique. Nous mettons tout en \u0153uvre pour que vous en profitiez pleinement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-740cb71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"740cb71\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-992ff15\" data-id=\"992ff15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39435f0 elementor-widget elementor-widget-heading\" data-id=\"39435f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Des appartements de vacances \u00e0 Roses pens\u00e9s pour votre confort<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44b3fc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44b3fc8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f62d36\" data-id=\"1f62d36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c76c930 elementor-widget elementor-widget-text-editor\" data-id=\"c76c930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Que vous arriviez en <a href=\"\/10-choses-a-faire-a-roses\/\">famille<\/a>, en couple ou entre amis, notre priorit\u00e9 est simple : votre confort et votre plaisir. Chaque appartement combine emplacement privil\u00e9gi\u00e9, \u00e9quipements soign\u00e9s et vue sur la mer &#8211; pour que vous profitiez du soleil, de la douceur de vivre catalane et du charme incomparable de la Costa Brava d\u00e8s le premier jour.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Nos appartements sont situ\u00e9s \u00e0 seulement 100 m\u00e8tres de la plage. Vous rejoignez la mer en quelques pas, rentrez d\u00e9jeuner sans effort et profitez des soir\u00e9es en toute s\u00e9r\u00e9nit\u00e9. C&rsquo;est cette proximit\u00e9 qui fait de notre r\u00e9sidence le point de d\u00e9part id\u00e9al pour <a href=\"\/visiter-cadaques-depuis-roses\/\">explorer<\/a> la r\u00e9gion.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28606c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28606c3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd7cd9b\" data-id=\"bd7cd9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-527d578 elementor-widget elementor-widget-heading\" data-id=\"527d578\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Roses, une destination baln\u00e9aire embl\u00e9matique de la Costa Brava<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f2f2e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f2f2e7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c32734\" data-id=\"2c32734\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ac55ea elementor-widget elementor-widget-text-editor\" data-id=\"8ac55ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Roses est une <a href=\"\/vacances-ete-roses-costa-brava\/\">destination baln\u00e9aire<\/a> embl\u00e9matique de la Costa Brava, en Catalogne. Longues plages de sable fin, criques pr\u00e9serv\u00e9es, port de plaisance anim\u00e9, arri\u00e8re-pays verdoyant &#8211; elle offre un cadre id\u00e9al pour des vacances au soleil. Amateur de farniente, de sports nautiques ou de <a href=\"\/parcs-naturels-roses\/\">randonn\u00e9e<\/a>, vous trouverez votre bonheur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2143d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2143d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9eaff42\" data-id=\"9eaff42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0c263b elementor-widget elementor-widget-heading\" data-id=\"a0c263b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Faut-il dire Roses ou Rosas ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdb62f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdb62f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4ce540\" data-id=\"b4ce540\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e341eab elementor-widget elementor-widget-text-editor\" data-id=\"e341eab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Vous trouverez les deux orthographes pour d\u00e9signer notre belle station baln\u00e9aire de la Costa Brava : <strong>Roses<\/strong> et <strong>Rosas<\/strong>. Pas de panique, c&rsquo;est bien la m\u00eame ville. <strong>Roses<\/strong> est le nom officiel actuel, en catalan, langue co-officielle de la r\u00e9gion avec l&rsquo;espagnol. <strong>Rosas<\/strong> est l&rsquo;ancienne d\u00e9nomination en castillan, encore largement utilis\u00e9e par les Fran\u00e7ais qui ont connu la r\u00e9gion dans les ann\u00e9es 1980-1990. Depuis le r\u00e9tablissement de l&rsquo;autonomie de la Catalogne en 1979, l&rsquo;usage officiel est revenu au catalan, et tous les panneaux, cartes et publications institutionnelles utilisent d\u00e9sormais Roses. Mais dans la vie courante, et notamment chez nos voisins espagnols hors Catalogne, Rosas reste tr\u00e8s r\u00e9pandu. Les deux noms d\u00e9signent le m\u00eame village de p\u00eacheurs devenu station baln\u00e9aire embl\u00e9matique de la Costa Brava, blottie au fond de sa magnifique baie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34b9dd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34b9dd7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03f280b\" data-id=\"03f280b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb702a2 elementor-widget elementor-widget-heading\" data-id=\"eb702a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Roses, facilement accessible depuis la France et toute l'Europe<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08e568c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08e568c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7be9a4\" data-id=\"f7be9a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fa068f elementor-widget elementor-widget-text-editor\" data-id=\"7fa068f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Roses est situ\u00e9e \u00e0 quelques kilom\u00e8tres seulement de la fronti\u00e8re fran\u00e7aise, ce qui en fait l&rsquo;une des destinations baln\u00e9aires les plus accessibles de M\u00e9diterran\u00e9e. En voiture depuis Perpignan, c&rsquo;est moins d&rsquo;une heure et demie. En train via le TGV Paris-Figueres, vous \u00eates sur place en un peu plus de 3 heures. Les a\u00e9roports de <a href=\"\/visiter-gerone-depuis-roses\/\">G\u00e9rone<\/a> et <a href=\"\/visiter-barcelone-depuis-roses\/\">Barcelone<\/a> compl\u00e8tent les options pour les voyageurs europ\u00e9ens.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4af93fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4af93fe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3be49f5\" data-id=\"3be49f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b8680b elementor-widget elementor-widget-heading\" data-id=\"1b8680b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Votre location \u00e0 Rosas en Espagne, directement chez le propri\u00e9taire<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-597ccf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"597ccf5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8318a84\" data-id=\"8318a84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87a8536 elementor-widget elementor-widget-text-editor\" data-id=\"87a8536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Vous cherchez une location \u00e0 Rosas en Espagne pour vos prochaines vacances sur la Costa Brava ? Roses Rentals vous propose deux appartements vue mer \u00e0 Canyelles Petites, le quartier r\u00e9sidentiel et pr\u00e9serv\u00e9 de Roses, \u00e0 deux minutes \u00e0 pied de la plage. Que vous soyez en famille ou en couple, nos appartements avec terrasse, parking et check-in autonome sont disponibles en r\u00e9servation directe, sans frais de plateforme et aux meilleurs prix garantis. Location Rosas, appartement Roses, s\u00e9jour Costa Brava : bienvenue chez nous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f58e051 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f58e051\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d6d2572\" data-id=\"5d6d2572\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-418a8ae7 elementor-widget elementor-widget-html\" data-id=\"418a8ae7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<style>\n#rental-list{\n    display: flex;\n    align-content:center;\n    justify-content: center;\n    flex-wrap:wrap;\n    margin: auto;\n    max-width:1580px;\n\n}\n\n.rental h5{\n    font-size:1.7rem;\n    font-weight:800;\n    color:#000;\n}\n.rental{\n    display:flex;\n    flex-direction:column;\n    justify-content:space-between;\n    width: 400px;\n    background-color: rgb(255, 255, 255);\n    border-radius: 10px;\n    margin:1%;\n    padding: 15px;\n    box-shadow: 0px 0px 15px 0px rgb(0 0 0 \/ 14%);\n}\n\n.rental-image {\n    width:100%;\n    height:370px;\n    background-size:cover;\n    display:block;\n    border-radius:7px;\n    -webkit-transition: all 0.5s 0s ease;\n-moz-transition: all 0.5s 0s ease;\n-o-transition: all 0.5s 0s ease;\ntransition: all 0.5s 0s ease;\n}\n\n.rental-image:hover{\n    transform:scale(103%);\n    box-shadow: 0px 5px 5px 0px rgb(0 0 0 \/ 4%);\n}\n\n.rental-content{\n    margin: 10px 10px 10px 10px;\n    padding: 10px 10px 10px 10px;\n}\n\n.rental .btn{\n    display:block;\n    text-align:center;\n    color: #fff;\n    border-radius:7px;\n    font-size: 1.2em;\n    font-weight: 800;\n    background-color: var( --e-global-color-primary );\n    padding: 0.7em 1em;\n    margin-top:1rem;\n    border:none;\n    text-transform: uppercase;\n    box-shadow: 0px 5px 15px 0px rgb(0 0 0 \/ 15%);\n    -webkit-transition: all 0.5s 0s ease;\n-moz-transition: all 0.5s 0s ease;\n-o-transition: all 0.5s 0s ease;\ntransition: all 0.5s 0s ease;\n}\n\n.rental .btn:hover{\n    background-color: var( --e-global-color-b5480b3 ); );\n    transform:scale(95%);\n}\n\n\n.rental-price {\n    font-size:120%;\n    text-transform: uppercase;\n}\n\n@media (max-width:992px) {\n    .rental h2{\n       font-size: 26px;\n    }\n    .rental{\n        min-height: 400px;\n    }\n}\n<\/style>\n\n<div id=\"rental-list\">\n<\/div>\n<script type=\"text\/javascript\">\n\nconst apiKey =  'BBMHpV5CartLvSt1TZV228B6n'\n\nfunction display(data){\n    \n    const rentalList = data.rentals;\n\n    rentalList.forEach(property => {\n        \n        if(property != undefined > 0){\n            \n        let {name, city, address, capacity, min_price, property_key} = property;\n        \n        let appartHTML = `\n          <div class=\"rental\">\n            <a class=\"rental-image\" style=\"background-image: url(${property.photos.length > 0 ? property.photos[0].name : 'https:\/\/app.superhote.com\/static\/assets\/images\/SuperHote_icons\/rent-black.png'})\" href=\"\/reservation?appart=${property_key}\"><\/a>\n            <div class=\"rental-content\">\n                <a href=\"\/reservation?appart=${property_key}\"><h5 class=\"rental-title\">${name}<\/h5><\/a>\n                <div class=\"rental-price\"> \u00c0 partir de <b>\u20ac${min_price}<\/b><\/div>\n                <div class=\"rental-details\">\n                  ${capacity} Voyageurs \u00b7 ${city}\n                <\/div>\n                <a class=\"btn\" href=\"\/reservation?appart=${property_key}\">R\u00e9server Maintenant<\/a>\n            <\/div>\n          <\/div>`;\n          \n         document.querySelector(\"#rental-list\").innerHTML += appartHTML;\n         \n        }\n    })\n    \n}\n\n\nfetch(`https:\/\/app.superhote.com\/api\/v2\/get-user-rentals\/${apiKey}`)\n  .then(response => response.json())\n  .then(json => display(json));\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5175312 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5175312\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59baf08\" data-id=\"59baf08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dd0d60 elementor-widget elementor-widget-html\" data-id=\"5dd0d60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?f7fa13966a6f618cce66976b33f\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f6b54db elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f6b54db\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11edf4b1\" data-id=\"11edf4b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67d7c57a elementor-widget elementor-widget-heading\" data-id=\"67d7c57a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Questions Fr\u00e9quentes<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a31c571 elementor-widget elementor-widget-heading\" data-id=\"1a31c571\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Vous vous les posez peut-\u00eatre aussi<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca83bd4 elementor-widget elementor-widget-toggle\" data-id=\"ca83bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2121\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2121\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelles sont les heures d'arriv\u00e9es et de d\u00e9part ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2121\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2121\"><p>L&rsquo;arrive\u0301e dans l\u2019appartement est possible d\u00e8s 17h00. Pour permettre l&rsquo;intervention de notre prestataire m\u00e9nage, vous devez lib\u00e9rer les lieux avant 10h00.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2122\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2122\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment se d\u00e9roule la remise des cl\u00e9s ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2122\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2122\"><p>Pour permettre un check-in autonome et flexible, une bo\u00eete \u00e0 cl\u00e9s s\u00e9curis\u00e9e vous permet d&rsquo;acc\u00e9der \u00e0 votre appartement \u00e0 toute heure.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2123\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2123\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Le parking est-il inclus ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2123\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2123\"><p>Chaque appartement dispose d&rsquo;une place attribu\u00e9e sur le parking de la r\u00e9sidence.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2124\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2124\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les draps sont-ils fournis ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2124\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2124\"><p>Les draps, les serviettes de toilette et le linge de maison (tapis de bain, essuie-main et torchon) sont fournis.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2125\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2125\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Le m\u00e9nage est-il inclus dans le s\u00e9jour ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2125\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2125\"><p>Les frais de me\u0301nage obligatoire sont en sus et s&rsquo;\u00e9l\u00e8vent \u00e0 70,00 EUR.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2126\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2126\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Annulation de location<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2126\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2126\"><p>Les re\u0301servations sont de\u0301finitives et non remboursables.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2127\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2127\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les animaux sont ils autoris\u00e9s ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2127\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2127\"><p>Nous aimons beaucoup les animaux mais ils ne sont pas admis, pour limiter les risques d&rsquo;allergie.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2128\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2128\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Est-il possible de fumer dans les logements ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2128\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2128\"><p>Il est strictement interdit de fumer dans les logements.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2129\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-2129\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Puis-je organiser des f\u00eates dans le logement ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2129\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-2129\"><p>Les f\u00eates et rassemblements sont interdits au sein de la r\u00e9sidence.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-21210\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-21210\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle est la capacit\u00e9 des appartements ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-21210\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-21210\"><p>Ils peuvent accueillir jusqu&rsquo;\u00e0 4 personnes dont au moins un adulte de plus de 18 ans. Cette limite est impos\u00e9e par l&rsquo;assureur des appartements, il ne peut y avoir aucune exception.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-21211\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-21211\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Etes-vous joignables durant le s\u00e9jour ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-21211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-21211\"><p>Nous restons disponibles pendant toute la dur\u00e9e de votre s\u00e9jour (coordonn\u00e9es sur la page \u00ab\u00a0Contact\u00a0\u00bb)<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vacances sur la Costa Brava Appartements vue mer \u00e0 Roses, \u00e0 100 m\u00e8tres de la plage Bienvenue chez Roses Rentals, votre location de vacances \u00e0 Rosas Bienvenue chez Roses Rentals, votre adresse pour une location de vacances \u00e0 Roses inoubliable, en Espagne. Nos appartements sont id\u00e9alement situ\u00e9s \u00e0 deux pas de la mer, au c\u0153ur [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-92","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Location vacances Roses Costa Brava | Appartements vue mer<\/title>\n<meta name=\"description\" content=\"Location vacances appartements vue mer \u00e0 Roses, Costa Brava. Plage \u00e0 100m, parking inclus, meilleurs prix garantis. Sans frais de plateforme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosesrentals.com\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roses Rentals : Location vacances Roses Costa Brava\" \/>\n<meta property=\"og:description\" content=\"Vos vacances \u00e0 Roses, Costa Brava, dans un appartement vue mer \u00e0 100m de la plage. R\u00e9servation directe chez le propri\u00e9taire, sans frais Airbnb ni Booking.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosesrentals.com\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Roses Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T15:28:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/03\/SolMar1-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Accueil\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"name\":\"Location vacances Roses Costa Brava | Appartements vue mer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\"},\"datePublished\":\"2023-04-06T10:28:43+00:00\",\"dateModified\":\"2026-05-14T15:28:19+00:00\",\"description\":\"Location vacances appartements vue mer \u00e0 Roses, Costa Brava. Plage \u00e0 100m, parking inclus, meilleurs prix garantis. Sans frais de plateforme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rosesrentals.com\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rosesrentals.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"name\":\"rosesrentals.com\",\"description\":\"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rosesrentals.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\",\"name\":\"roses Rentals\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rosesrentals\",\"https:\\\/\\\/www.instagram.com\\\/rosesrentals\"],\"description\":\"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.\",\"telephone\":[],\"openingHoursSpecification\":[]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"width\":150,\"height\":150,\"caption\":\"roses Rentals\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Location vacances Roses Costa Brava | Appartements vue mer","description":"Location vacances appartements vue mer \u00e0 Roses, Costa Brava. Plage \u00e0 100m, parking inclus, meilleurs prix garantis. Sans frais de plateforme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosesrentals.com\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Roses Rentals : Location vacances Roses Costa Brava","og_description":"Vos vacances \u00e0 Roses, Costa Brava, dans un appartement vue mer \u00e0 100m de la plage. R\u00e9servation directe chez le propri\u00e9taire, sans frais Airbnb ni Booking.","og_url":"https:\/\/www.rosesrentals.com\/fr\/","og_site_name":"Roses Rentals","article_publisher":"https:\/\/www.facebook.com\/rosesrentals","article_modified_time":"2026-05-14T15:28:19+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/03\/SolMar1-10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Accueil","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rosesrentals.com\/","url":"https:\/\/www.rosesrentals.com\/","name":"Location vacances Roses Costa Brava | Appartements vue mer","isPartOf":{"@id":"https:\/\/www.rosesrentals.com\/#website"},"datePublished":"2023-04-06T10:28:43+00:00","dateModified":"2026-05-14T15:28:19+00:00","description":"Location vacances appartements vue mer \u00e0 Roses, Costa Brava. Plage \u00e0 100m, parking inclus, meilleurs prix garantis. Sans frais de plateforme.","breadcrumb":{"@id":"https:\/\/www.rosesrentals.com\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosesrentals.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosesrentals.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rosesrentals.com\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/www.rosesrentals.com\/#website","url":"https:\/\/www.rosesrentals.com\/","name":"rosesrentals.com","description":"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals","publisher":{"@id":"https:\/\/www.rosesrentals.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosesrentals.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Organization","Place"],"@id":"https:\/\/www.rosesrentals.com\/#organization","name":"roses Rentals","url":"https:\/\/www.rosesrentals.com\/","logo":{"@id":"https:\/\/www.rosesrentals.com\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.rosesrentals.com\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/rosesrentals","https:\/\/www.instagram.com\/rosesrentals"],"description":"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.","telephone":[],"openingHoursSpecification":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rosesrentals.com\/#local-main-organization-logo","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","width":150,"height":150,"caption":"roses Rentals"}]}},"_links":{"self":[{"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/pages\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":550,"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/pages\/92\/revisions"}],"predecessor-version":[{"id":4581,"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/pages\/92\/revisions\/4581"}],"wp:attachment":[{"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/media?parent=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}