{"id":2360,"date":"2026-03-08T18:09:40","date_gmt":"2026-03-08T18:09:40","guid":{"rendered":"https:\/\/www.rosesrentals.com\/?page_id=2360"},"modified":"2026-05-14T15:31:03","modified_gmt":"2026-05-14T15:31:03","slug":"appartement-renove-roses-canyelles","status":"publish","type":"page","link":"https:\/\/www.rosesrentals.com\/fr\/appartement-renove-roses-canyelles\/","title":{"rendered":"Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses Canyelles Petites plage \u00e0 2 minutes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2360\" class=\"elementor elementor-2360\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4774ed95 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4774ed95\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68262b9a\" data-id=\"68262b9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13960d34 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"13960d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Vacances sur la Costa Brava<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86773f7 animated-slow elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"86773f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87c9bad animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"87c9bad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses, plage \u00e0 pied<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efc3fd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efc3fd8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b82ee3\" data-id=\"7b82ee3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcd523e elementor-widget elementor-widget-spacer\" data-id=\"bcd523e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e140319 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e140319\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7daf919\" data-id=\"7daf919\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdc6b2e elementor-widget elementor-widget-heading\" data-id=\"bdc6b2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Un appartement neuf face \u00e0 la M\u00e9diterran\u00e9e<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40676ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40676ff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5200e8\" data-id=\"c5200e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccbd9c0 elementor-widget elementor-widget-text-editor\" data-id=\"ccbd9c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cet appartement enti\u00e8rement r\u00e9nov\u00e9 en 2023 \u00e0 Roses Costa Brava au premier \u00e9tage d&rsquo;une petite r\u00e9sidence calme de <a href=\"https:\/\/visit.roses.cat\/fr\/decouvrir\/plages-et-criques\/plage-canyelles-petites.html\">Canyelles Petites<\/a> combine le charme de la Costa Brava et le confort d&rsquo;un logement moderne. La <a href=\"\/plages-roses-costa-brava\/\" target=\"_blank\" rel=\"noopener\">plage de Canyelles<\/a> est \u00e0 2 minutes \u00e0 pied. La terrasse donne directement sur la baie.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Pour 4 voyageurs &#8211; familles, couples ou amis &#8211; c&rsquo;est une base id\u00e9ale pour d\u00e9couvrir Roses (Rosas) et ses environs : restaurants \u00e0 deux pas, navette vers le centre-ville, parcs naturels accessibles en voiture. Et \u00e0 votre arriv\u00e9e, un kit de bienvenue avec eau et Cava vous attend.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4cd8b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4cd8b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9732248\" data-id=\"9732248\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16dd89c elementor-widget elementor-widget-html\" data-id=\"16dd89c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?760800667a36359e2296f374abe\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-740cb71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"740cb71\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-992ff15\" data-id=\"992ff15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39435f0 elementor-widget elementor-widget-heading\" data-id=\"39435f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Terrasse vue mer et salon ouvert sur la M\u00e9diterran\u00e9e<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44b3fc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44b3fc8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f62d36\" data-id=\"1f62d36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c76c930 elementor-widget elementor-widget-text-editor\" data-id=\"c76c930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La terrasse de 10 m\u00b2 est une v\u00e9ritable pi\u00e8ce \u00e0 vivre suppl\u00e9mentaire. Table, chaises, banquette-coussin et store-banne : tout y est pour profiter du spectacle de la <a href=\"\/restaurants-canyelles-petites-roses\/\">baie de Canyelles<\/a> du matin au soir.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u00c0 l&rsquo;int\u00e9rieur, le salon s&rsquo;ouvre largement sur cet espace ext\u00e9rieur gr\u00e2ce \u00e0 une baie vitr\u00e9e. La lumi\u00e8re naturelle y est omnipr\u00e9sente. Canap\u00e9, t\u00e9l\u00e9vision connect\u00e9e (Netflix, Prime Video, VPN disponible), table pliante et ventilateur de plafond compl\u00e8tent cet espace \u00e0 la fois reposant et fonctionnel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28606c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28606c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd7cd9b\" data-id=\"bd7cd9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-527d578 elementor-widget elementor-widget-heading\" data-id=\"527d578\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">L'appartement en d\u00e9tail<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f2f2e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f2f2e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c32734\" data-id=\"2c32734\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ac55ea elementor-widget elementor-widget-text-editor\" data-id=\"8ac55ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>S\u00e9jour<\/strong><\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\">Salon lumineux ouvert sur la terrasse<\/li><li class=\"whitespace-normal break-words pl-2\">Canap\u00e9 et table pliante (coin repas ou t\u00e9l\u00e9travail)<\/li><li class=\"whitespace-normal break-words pl-2\">T\u00e9l\u00e9vision connect\u00e9e : Netflix, Prime Video, VPN disponible<\/li><li class=\"whitespace-normal break-words pl-2\">Climatisation et ventilateur de plafond<\/li><\/ul><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Cuisine<\/strong><\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\">Enti\u00e8rement \u00e9quip\u00e9e et r\u00e9nov\u00e9e<\/li><li class=\"whitespace-normal break-words pl-2\">Four Samsung, micro-ondes combin\u00e9 grill, plaques de cuisson<\/li><li class=\"whitespace-normal break-words pl-2\">R\u00e9frig\u00e9rateur-cong\u00e9lateur, lave-linge, grille-pain, bouilloire<\/li><li class=\"whitespace-normal break-words pl-2\">Machine \u00e0 caf\u00e9 filtre et L&rsquo;Or Barista compatible Nespresso<\/li><li class=\"whitespace-normal break-words pl-2\">Ustensiles et vaisselle complets<\/li><\/ul><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Chambres<\/strong><\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\">Chambre 1 (c\u00f4t\u00e9 plage) : grand lit double 150\u00d7200 cm, vue mer, coffre-fort, placard<\/li><li class=\"whitespace-normal break-words pl-2\">Chambre 2 (c\u00f4t\u00e9 cour) : deux lits simples 80\u00d7200 cm modulables, vue sur jardin verdoyant<\/li><\/ul><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Salle de bain<\/strong><\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\">Douche \u00e0 l&rsquo;italienne moderne<\/li><li class=\"whitespace-normal break-words pl-2\">Miroir lumineux, rangements<\/li><li class=\"whitespace-normal break-words pl-2\">S\u00e8che-cheveux et produits de premi\u00e8re n\u00e9cessit\u00e9 inclus<\/li><\/ul><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Confort &amp; services<\/strong><\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\">Wi-Fi haut d\u00e9bit (fibre)<\/li><li class=\"whitespace-normal break-words pl-2\">Linge de lit, serviettes de bain et tapis de bain fournis<\/li><li class=\"whitespace-normal break-words pl-2\">Lit b\u00e9b\u00e9 et chaise haute disponibles sur demande<\/li><li class=\"whitespace-normal break-words pl-2\">Barbecue communautaire<\/li><li class=\"whitespace-normal break-words pl-2\">Parking priv\u00e9 au pied de la r\u00e9sidence<\/li><li class=\"whitespace-normal break-words pl-2\">Kit de bienvenue : eau et Cava offerts \u00e0 l&rsquo;arriv\u00e9e<\/li><li class=\"whitespace-normal break-words pl-2\"><a href=\"https:\/\/www.rosesrentals.com\/ou-faire-ses-courses-a-roses-marches-supermarches-et-bonnes-adresses\/\">Check-in autonome<\/a> par bo\u00eete \u00e0 cl\u00e9s connect\u00e9e d\u00e8s 17h<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34b9dd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34b9dd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03f280b\" data-id=\"03f280b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb702a2 elementor-widget elementor-widget-heading\" data-id=\"eb702a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Informations pratiques<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08e568c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08e568c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7be9a4\" data-id=\"f7be9a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fa068f elementor-widget elementor-widget-text-editor\" data-id=\"7fa068f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Capacit\u00e9 :<\/strong> 4 voyageurs &#8211; 2 chambres &#8211; 1 salle de bain <strong>\u00c9tage :<\/strong> Premier \u00e9tage <strong>R\u00e9novation :<\/strong> 2023 <strong>Localisation :<\/strong> Canyelles Petites, Roses &#8211; plage \u00e0 2 minutes \u00e0 pied <strong>Arriv\u00e9e :<\/strong> \u00c0 partir de 17h00 &#8211; d\u00e9part avant 10h00 <strong>Animaux :<\/strong> Non admis <strong>Fumeurs :<\/strong> Non autoris\u00e9 <strong>Num\u00e9ro de registre :<\/strong> HUTG-066697-30<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Taxe de s\u00e9jour :<\/strong> \u00c0 r\u00e9gler sur place, par nuit et par personne de 17 ans et plus (dans la limite de 7 jours). Non incluse dans le prix de la r\u00e9servation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db9a55e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db9a55e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aee90ee\" data-id=\"aee90ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-629d6ba elementor-widget elementor-widget-heading\" data-id=\"629d6ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quentes sur cet appartement<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d9369c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d9369c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a1092e\" data-id=\"9a1092e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c38ad52 elementor-widget elementor-widget-text-editor\" data-id=\"c38ad52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>L&rsquo;appartement a-t-il vraiment \u00e9t\u00e9 enti\u00e8rement r\u00e9nov\u00e9 ?<\/strong> Oui, la r\u00e9novation compl\u00e8te a \u00e9t\u00e9 r\u00e9alis\u00e9e en 2023 : cuisine, salle de bain, d\u00e9coration et \u00e9quipements sont tous neufs. C&rsquo;est ce que nos locataires mentionnent en premier dans leurs avis \u00e0 propos de cet appartement r\u00e9nov\u00e9 \u00e0 Roses Costa Brava.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>La plage de Canyelles est-elle vraiment \u00e0 2 minutes ?<\/strong> Oui, la <a href=\"\/plages-roses-costa-brava\/\">plage de Canyelles Petites<\/a> est accessible \u00e0 pied en moins de 2 minutes depuis la r\u00e9sidence. C&rsquo;est l&rsquo;un des grands avantages de cet emplacement.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Y a-t-il un barbecue ?<\/strong> Oui, une zone ext\u00e9rieure partag\u00e9e avec barbecue au charbon et transats est \u00e0 disposition des locataires de la r\u00e9sidence.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>La navette pour le centre de Roses est-elle proche ?<\/strong> L&rsquo;arr\u00eat de navette est \u00e0 quelques pas de la r\u00e9sidence. C&rsquo;est pratique pour explorer le port et le centre-ville de Roses sans voiture.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Qu&rsquo;est-ce que le kit de bienvenue ?<\/strong> \u00c0 votre arriv\u00e9e, vous trouverez de l&rsquo;eau et une bouteille de Cava (mousseux catalan) offerts par Philippe et Olivier &#8211; une petite attention pour d\u00e9marrer vos vacances du bon pied.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vacances sur la Costa Brava Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses, plage \u00e0 pied Un appartement neuf face \u00e0 la M\u00e9diterran\u00e9e Cet appartement enti\u00e8rement r\u00e9nov\u00e9 en 2023 \u00e0 Roses Costa Brava au premier \u00e9tage d&rsquo;une petite r\u00e9sidence calme de Canyelles Petites combine le charme de la Costa Brava et le confort d&rsquo;un logement moderne. La [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2360","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses Costa Brava, 2 chambres<\/title>\n<meta name=\"description\" content=\"Appartement r\u00e9nov\u00e9 en 2023 \u00e0 Roses Costa Brava. Vue mer, terrasse, plage \u00e0 2 minutes, parking. 2 chambres, 4 personnes. R\u00e9servation directe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosesrentals.com\/fr\/appartement-renove-roses-canyelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses Canyelles Petites plage \u00e0 2 minutes\" \/>\n<meta property=\"og:description\" content=\"Appartement r\u00e9nov\u00e9 en 2023 \u00e0 Roses Costa Brava. Vue mer, terrasse, plage \u00e0 2 minutes, parking. 2 chambres, 4 personnes. R\u00e9servation directe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosesrentals.com\/fr\/appartement-renove-roses-canyelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Roses Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T15:31:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/appartement-renove-roses-canyelles\\\/\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/appartement-renove-roses-canyelles\\\/\",\"name\":\"Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses Costa Brava, 2 chambres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\"},\"datePublished\":\"2026-03-08T18:09:40+00:00\",\"dateModified\":\"2026-05-14T15:31:03+00:00\",\"description\":\"Appartement r\u00e9nov\u00e9 en 2023 \u00e0 Roses Costa Brava. Vue mer, terrasse, plage \u00e0 2 minutes, parking. 2 chambres, 4 personnes. R\u00e9servation directe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/appartement-renove-roses-canyelles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rosesrentals.com\\\/appartement-renove-roses-canyelles\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/appartement-renove-roses-canyelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rosesrentals.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses Canyelles Petites plage \u00e0 2 minutes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"name\":\"rosesrentals.com\",\"description\":\"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rosesrentals.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\",\"name\":\"roses Rentals\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/appartement-renove-roses-canyelles\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/appartement-renove-roses-canyelles\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rosesrentals\",\"https:\\\/\\\/www.instagram.com\\\/rosesrentals\"],\"description\":\"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.\",\"telephone\":[],\"openingHoursSpecification\":[]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/appartement-renove-roses-canyelles\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"width\":150,\"height\":150,\"caption\":\"roses Rentals\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses Costa Brava, 2 chambres","description":"Appartement r\u00e9nov\u00e9 en 2023 \u00e0 Roses Costa Brava. Vue mer, terrasse, plage \u00e0 2 minutes, parking. 2 chambres, 4 personnes. R\u00e9servation directe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosesrentals.com\/fr\/appartement-renove-roses-canyelles\/","og_locale":"fr_FR","og_type":"article","og_title":"Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses Canyelles Petites plage \u00e0 2 minutes","og_description":"Appartement r\u00e9nov\u00e9 en 2023 \u00e0 Roses Costa Brava. Vue mer, terrasse, plage \u00e0 2 minutes, parking. 2 chambres, 4 personnes. R\u00e9servation directe.","og_url":"https:\/\/www.rosesrentals.com\/fr\/appartement-renove-roses-canyelles\/","og_site_name":"Roses Rentals","article_publisher":"https:\/\/www.facebook.com\/rosesrentals","article_modified_time":"2026-05-14T15:31:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/","url":"https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/","name":"Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses Costa Brava, 2 chambres","isPartOf":{"@id":"https:\/\/www.rosesrentals.com\/#website"},"datePublished":"2026-03-08T18:09:40+00:00","dateModified":"2026-05-14T15:31:03+00:00","description":"Appartement r\u00e9nov\u00e9 en 2023 \u00e0 Roses Costa Brava. Vue mer, terrasse, plage \u00e0 2 minutes, parking. 2 chambres, 4 personnes. R\u00e9servation directe.","breadcrumb":{"@id":"https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rosesrentals.com\/"},{"@type":"ListItem","position":2,"name":"Appartement r\u00e9nov\u00e9 vue mer \u00e0 Roses Canyelles Petites plage \u00e0 2 minutes"}]},{"@type":"WebSite","@id":"https:\/\/www.rosesrentals.com\/#website","url":"https:\/\/www.rosesrentals.com\/","name":"rosesrentals.com","description":"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals","publisher":{"@id":"https:\/\/www.rosesrentals.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosesrentals.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Organization","Place"],"@id":"https:\/\/www.rosesrentals.com\/#organization","name":"roses Rentals","url":"https:\/\/www.rosesrentals.com\/","logo":{"@id":"https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/rosesrentals","https:\/\/www.instagram.com\/rosesrentals"],"description":"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.","telephone":[],"openingHoursSpecification":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/#local-main-organization-logo","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","width":150,"height":150,"caption":"roses Rentals"}]}},"_links":{"self":[{"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/pages\/2360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/comments?post=2360"}],"version-history":[{"count":157,"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/pages\/2360\/revisions"}],"predecessor-version":[{"id":4593,"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/pages\/2360\/revisions\/4593"}],"wp:attachment":[{"href":"https:\/\/www.rosesrentals.com\/fr\/wp-json\/wp\/v2\/media?parent=2360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}