{"id":70,"date":"2023-04-06T10:28:42","date_gmt":"2023-04-06T10:28:42","guid":{"rendered":"https:\/\/rosaslocation.com\/politique-de-confidentialite\/"},"modified":"2026-05-12T15:12:18","modified_gmt":"2026-05-12T15:12:18","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/www.rosesrentals.com\/es\/politique-de-confidentialite\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"70\" class=\"elementor elementor-70\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b1d7cf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b1d7cf4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d499272\" data-id=\"d499272\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-652b8e7 elementor-widget elementor-widget-heading\" data-id=\"652b8e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Appartements vue mer \u00e0 Roses, \u00e0 100 m\u00e8tres de la plage<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b744d69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b744d69\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49234f38\" data-id=\"49234f38\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-591b8f4d elementor-widget elementor-widget-text-editor\" data-id=\"591b8f4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"3a4b3077\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><em>Derni\u00e8re mise \u00e0 jour : mars 2026<\/em><\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">D\u00e9finitions<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">L&rsquo;\u00c9diteur : Philippe Cantegreil propri\u00e9taire du site <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"http:\/\/www.rosesrentals.com\">www.rosesrentals.com<\/a>, ci-apr\u00e8s \u00ab nous \u00bb ou \u00ab l&rsquo;\u00c9diteur \u00bb.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Le Site : <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"http:\/\/www.rosesrentals.com\">www.rosesrentals.com<\/a><\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">L&rsquo;Utilisateur : Toute personne naviguant sur le Site ou effectuant une r\u00e9servation, ci-apr\u00e8s \u00ab vous \u00bb.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Sous-traitants : Les prestataires tiers intervenant dans le traitement des donn\u00e9es (SuprHote, Stripe, Trustindex, Infomaniak).<\/p><h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">1 &#8211; Donn\u00e9es collect\u00e9es<\/h3><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Dans le cadre de l&rsquo;utilisation du Site et du service de location saisonni\u00e8re, nous collectons les donn\u00e9es suivantes :<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Via le formulaire de contact : nom, pr\u00e9nom, adresse e-mail, message libre.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Via le moteur de r\u00e9servation (SuperHote) : nom, pr\u00e9nom, adresse e-mail, num\u00e9ro de t\u00e9l\u00e9phone, dates de s\u00e9jour, nombre d&rsquo;occupants.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Via le paiement (Stripe) : donn\u00e9es de paiement par carte bancaire. Ces donn\u00e9es sont trait\u00e9es directement et exclusivement par Stripe &#8211; nous n&rsquo;avons \u00e0 aucun moment acc\u00e8s \u00e0 vos coordonn\u00e9es bancaires compl\u00e8tes.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Via les avis voyageurs (Trustindex) : pr\u00e9nom, note et commentaire laiss\u00e9s volontairement par les locataires.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Donn\u00e9es de navigation collect\u00e9es automatiquement : adresse IP, type de navigateur, pages consult\u00e9es, dur\u00e9e de visite &#8211; \u00e0 des fins de mesure d&rsquo;audience uniquement.<\/p><h3 class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">2 &#8211; Finalit\u00e9s du traitement<\/h3><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Vos donn\u00e9es sont collect\u00e9es et trait\u00e9es exclusivement pour les finalit\u00e9s suivantes :<\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\">Gestion des demandes de contact et de renseignements<\/li><li class=\"whitespace-normal break-words pl-2\">Traitement et suivi des r\u00e9servations de location saisonni\u00e8re<\/li><li class=\"whitespace-normal break-words pl-2\">Traitement s\u00e9curis\u00e9 des paiements via Stripe<\/li><li class=\"whitespace-normal break-words pl-2\">Envoi de communications li\u00e9es \u00e0 votre r\u00e9servation (confirmation, rappels, check-in)<\/li><li class=\"whitespace-normal break-words pl-2\">Envoi de notre newsletter, uniquement si vous y avez express\u00e9ment consenti<\/li><li class=\"whitespace-normal break-words pl-2\">Am\u00e9lioration du Site via la mesure d&rsquo;audience anonymis\u00e9e<\/li><li class=\"whitespace-normal break-words pl-2\">Affichage des avis voyageurs via Trustindex<\/li><\/ul><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Nous ne traitons pas vos donn\u00e9es \u00e0 des fins publicitaires, de revente \u00e0 des tiers ou de profilage commercial.<\/p><h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">3 \u2013 Base l\u00e9gale du traitement<\/h3><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Selon les cas, le traitement de vos donn\u00e9es repose sur :<\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\">L&rsquo;ex\u00e9cution du contrat de location (r\u00e9servation, paiement, gestion du s\u00e9jour)<\/li><li class=\"whitespace-normal break-words pl-2\">Votre consentement (newsletter, cookies non essentiels)<\/li><li class=\"whitespace-normal break-words pl-2\">Notre int\u00e9r\u00eat l\u00e9gitime (s\u00e9curit\u00e9 du site, mesure d&rsquo;audience)<\/li><li class=\"whitespace-normal break-words pl-2\">Le respect d&rsquo;une obligation l\u00e9gale (conservation des donn\u00e9es comptables)<\/li><\/ul><h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">4 &#8211; Sous-traitants et transferts de donn\u00e9es<\/h3><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Pour assurer le fonctionnement du Site et du service de r\u00e9servation, nous faisons appel aux sous-traitants suivants :<\/p><div class=\"overflow-x-auto w-full px-2 mb-6\"><table class=\"min-w-full border-collapse text-sm leading-[1.7] whitespace-normal\"><thead class=\"text-left\"><tr><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Prestataire<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">R\u00f4le<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Politique de confidentialit\u00e9<\/th><\/tr><\/thead><tbody><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">SuperHote<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Gestion des r\u00e9servations et channel manager<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\"><a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.superhote.com\/legal\/privacy\" target=\"_blank\" rel=\"noopener\">superhote.com\/legal\/privacy<\/a><\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Stripe<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Traitement des paiements s\u00e9curis\u00e9s<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\"><a href=\"http:\/\/stripe.com\/fr\/privacy\" target=\"_blank\" rel=\"noopener\">stripe.com\/fr\/privacy<\/a><\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Trustindex<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Collecte et affichage des avis voyageurs<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\"><a href=\"http:\/\/trustindex.io\/privacy-policy\" target=\"_blank\" rel=\"noopener\">trustindex.io\/privacy-policy<\/a><\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Infomaniak<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">H\u00e9bergement du site<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\"><a href=\"https:\/\/www.infomaniak.com\/fr\/cgv\/politique-de-confidentialite\" target=\"_blank\" rel=\"noopener\">https:\/\/www.infomaniak.com\/fr\/cgv\/politique-de-confidentialite<\/a><\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Google<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Mesure d&rsquo;audience (si Google Analytics activ\u00e9)<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\"><a href=\"http:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">policies.google.com\/privacy<\/a><\/td><\/tr><\/tbody><\/table><\/div><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ces prestataires agissent en qualit\u00e9 de sous-traitants et s&rsquo;engagent \u00e0 respecter le RGPD. Aucun transfert de donn\u00e9es n&rsquo;est effectu\u00e9 en dehors de l&rsquo;Union Europ\u00e9enne, \u00e0 l&rsquo;exception de Stripe et Google dont les serveurs peuvent \u00eatre localis\u00e9s aux \u00c9tats-Unis, dans le cadre de garanties appropri\u00e9es (clauses contractuelles types).<\/p><h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">5 &#8211; Dur\u00e9e de conservation des donn\u00e9es<\/h3><div class=\"overflow-x-auto w-full px-2 mb-6\"><table class=\"min-w-full border-collapse text-sm leading-[1.7] whitespace-normal\"><thead class=\"text-left\"><tr><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Type de donn\u00e9es<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Dur\u00e9e de conservation<\/th><\/tr><\/thead><tbody><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Donn\u00e9es de r\u00e9servation<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">5 ans \u00e0 compter de la fin du s\u00e9jour (obligation comptable)<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Donn\u00e9es de contact (formulaire)<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">3 ans \u00e0 compter du dernier contact<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Donn\u00e9es de paiement<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">G\u00e9r\u00e9es par Stripe selon leurs propres r\u00e8gles<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Cookies de mesure d&rsquo;audience<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">13 mois maximum<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Donn\u00e9es newsletter<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Jusqu&rsquo;\u00e0 d\u00e9sinscription<\/td><\/tr><\/tbody><\/table><\/div><h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">6 &#8211; Cookies<\/h3><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Le Site utilise les types de cookies suivants :<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cookies strictement n\u00e9cessaires (pas de consentement requis) : assurent le bon fonctionnement du site (session, s\u00e9curit\u00e9, panier de r\u00e9servation).<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cookies de mesure d&rsquo;audience (consentement requis) : permettent de mesurer le trafic et d&rsquo;am\u00e9liorer le site. Ces cookies ne sont d\u00e9pos\u00e9s qu&rsquo;apr\u00e8s votre consentement explicite via le bandeau affich\u00e9 lors de votre premi\u00e8re visite.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cookies tiers (consentement requis) : li\u00e9s aux services Trustindex (avis), SuprHote (moteur de r\u00e9servation) et \u00e9ventuellement aux r\u00e9seaux sociaux (boutons de partage).<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Vous pouvez \u00e0 tout moment modifier vos pr\u00e9f\u00e9rences cookies via le bandeau de gestion disponible en bas de chaque page, ou en configurant votre navigateur.<\/p><h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">7 &#8211; Vos droits<\/h3><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Conform\u00e9ment au RGPD (R\u00e8glement UE 2016\/679) et \u00e0 la loi Informatique et Libert\u00e9s modifi\u00e9e, vous disposez des droits suivants sur vos donn\u00e9es personnelles :<\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\">Droit d&rsquo;acc\u00e8s : obtenir une copie des donn\u00e9es vous concernant<\/li><li class=\"whitespace-normal break-words pl-2\">Droit de rectification : corriger des donn\u00e9es inexactes ou incompl\u00e8tes<\/li><li class=\"whitespace-normal break-words pl-2\">Droit \u00e0 l&rsquo;effacement : demander la suppression de vos donn\u00e9es<\/li><li class=\"whitespace-normal break-words pl-2\">Droit \u00e0 la portabilit\u00e9 : recevoir vos donn\u00e9es dans un format structur\u00e9 et r\u00e9utilisable<\/li><li class=\"whitespace-normal break-words pl-2\">Droit d&rsquo;opposition : vous opposer \u00e0 un traitement bas\u00e9 sur notre int\u00e9r\u00eat l\u00e9gitime<\/li><li class=\"whitespace-normal break-words pl-2\">Droit de retrait du consentement : retirer \u00e0 tout moment votre consentement (newsletter, cookies)<\/li><\/ul><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Pour exercer vos droits, contactez-nous par e-mail \u00e0 : contact[@]rosesrentals.com<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Nous nous engageons \u00e0 r\u00e9pondre dans un d\u00e9lai maximum d&rsquo;un mois. En cas de r\u00e9ponse insatisfaisante, vous disposez du droit d&rsquo;introduire une r\u00e9clamation aupr\u00e8s de la <strong>CNIL<\/strong> : <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"http:\/\/www.cnil.fr\">www.cnil.fr<\/a><\/p><h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">8 &#8211; S\u00e9curit\u00e9 des donn\u00e9es<\/h3><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Nous mettons en \u0153uvre les mesures techniques et organisationnelles appropri\u00e9es pour prot\u00e9ger vos donn\u00e9es contre tout acc\u00e8s non autoris\u00e9, perte ou divulgation. Les paiements sont trait\u00e9s par Stripe avec un chiffrement AES-256 bits de niveau bancaire. En cas de violation de donn\u00e9es susceptible d&rsquo;engendrer un risque pour vos droits et libert\u00e9s, nous nous engageons \u00e0 vous en informer dans les meilleurs d\u00e9lais.<\/p><h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">9 &#8211; Modifications de la politique de confidentialit\u00e9<\/h3><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La pr\u00e9sente politique peut \u00eatre mise \u00e0 jour pour refl\u00e9ter les \u00e9volutions l\u00e9gales ou de nos pratiques. La date de derni\u00e8re mise \u00e0 jour est indiqu\u00e9e en haut du document. En cas de modification substantielle, nous vous en informerons par e-mail si vous \u00eates client ou abonn\u00e9 \u00e0 notre newsletter.<\/p><h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">10 &#8211; Contact et r\u00e9clamations<\/h3><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Responsable du traitement : Philippe Cantegreil &#8211; contact[@]rosesrentals.com<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Autorit\u00e9 de contr\u00f4le comp\u00e9tente : Commission Nationale de l&rsquo;Informatique et des Libert\u00e9s (CNIL) 3 Place de Fontenoy 75007 Paris.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Appartements vue mer \u00e0 Roses, \u00e0 100 m\u00e8tres de la plage Derni\u00e8re mise \u00e0 jour : mars 2026 D\u00e9finitions L&rsquo;\u00c9diteur : Philippe Cantegreil propri\u00e9taire du site www.rosesrentals.com, ci-apr\u00e8s \u00ab nous \u00bb ou \u00ab l&rsquo;\u00c9diteur \u00bb. Le Site : www.rosesrentals.com L&rsquo;Utilisateur : Toute personne naviguant sur le Site ou effectuant une r\u00e9servation, ci-apr\u00e8s \u00ab vous \u00bb. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-70","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 | Roses Rentals<\/title>\n<meta name=\"description\" content=\"Pour tout savoir de la Politique de confidentialit\u00e9 du site rosesrentals.com qui propose des appartements en location \u00e0 Roses Costa Brava\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosesrentals.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Pour tout savoir de la Politique de confidentialit\u00e9 du site rosesrentals.com qui propose des appartements en location \u00e0 Roses Costa Brava\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosesrentals.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Roses Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T15:12:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 | Roses Rentals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\"},\"datePublished\":\"2023-04-06T10:28:42+00:00\",\"dateModified\":\"2026-05-12T15:12:18+00:00\",\"description\":\"Pour tout savoir de la Politique de confidentialit\u00e9 du site rosesrentals.com qui propose des appartements en location \u00e0 Roses Costa Brava\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rosesrentals.com\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rosesrentals.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"name\":\"rosesrentals.com\",\"description\":\"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rosesrentals.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\",\"name\":\"roses Rentals\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/politique-de-confidentialite\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/politique-de-confidentialite\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rosesrentals\",\"https:\\\/\\\/www.instagram.com\\\/rosesrentals\"],\"description\":\"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.\",\"telephone\":[],\"openingHoursSpecification\":[]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/politique-de-confidentialite\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"width\":150,\"height\":150,\"caption\":\"roses Rentals\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad | Roses Rentals","description":"Para saberlo todo sobre la Pol\u00edtica de privacidad del sitio rosesrentals.com, que ofrece apartamentos en alquiler en Roses Costa Brava.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosesrentals.com\/es\/politica-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Politique de confidentialit\u00e9","og_description":"Pour tout savoir de la Politique de confidentialit\u00e9 du site rosesrentals.com qui propose des appartements en location \u00e0 Roses Costa Brava","og_url":"https:\/\/www.rosesrentals.com\/es\/politica-de-privacidad\/","og_site_name":"Roses Rentals","article_publisher":"https:\/\/www.facebook.com\/rosesrentals","article_modified_time":"2026-05-12T15:12:18+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rosesrentals.com\/politique-de-confidentialite\/","url":"https:\/\/www.rosesrentals.com\/politique-de-confidentialite\/","name":"Pol\u00edtica de privacidad | Roses Rentals","isPartOf":{"@id":"https:\/\/www.rosesrentals.com\/#website"},"datePublished":"2023-04-06T10:28:42+00:00","dateModified":"2026-05-12T15:12:18+00:00","description":"Para saberlo todo sobre la Pol\u00edtica de privacidad del sitio rosesrentals.com, que ofrece apartamentos en alquiler en Roses Costa Brava.","breadcrumb":{"@id":"https:\/\/www.rosesrentals.com\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosesrentals.com\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosesrentals.com\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rosesrentals.com\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.rosesrentals.com\/#website","url":"https:\/\/www.rosesrentals.com\/","name":"rosesrentals.com","description":"Ubicaci\u00f3n de vacaciones Roses Costa Brava | Apartamentos con vistas al mar - Roses Rentals","publisher":{"@id":"https:\/\/www.rosesrentals.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosesrentals.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place"],"@id":"https:\/\/www.rosesrentals.com\/#organization","name":"Alquiler de rosas","url":"https:\/\/www.rosesrentals.com\/","logo":{"@id":"https:\/\/www.rosesrentals.com\/politique-de-confidentialite\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.rosesrentals.com\/politique-de-confidentialite\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/rosesrentals","https:\/\/www.instagram.com\/rosesrentals"],"description":"Roses Rentals es una casa de vacaciones directa que ofrece dos apartamentos con vistas al mar en Roses, en la Costa Brava de Catalu\u00f1a, Espa\u00f1a. Ubicados en la zona residencial de Canyelles Petites, a dos minutos a pie de la playa, nuestros apartamentos tienen capacidad para 4 personas en un entorno tranquilo y aut\u00e9ntico. Terrazas con vistas al mar, aparcamiento incluido, check-in aut\u00f3nomo. Reserva directa sin comisiones de plataforma, mejores precios garantizados. Ideal para vacaciones en familia o en pareja en la Costa Brava.","telephone":[],"openingHoursSpecification":[]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rosesrentals.com\/politique-de-confidentialite\/#local-main-organization-logo","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","width":150,"height":150,"caption":"roses Rentals"}]}},"_links":{"self":[{"href":"https:\/\/www.rosesrentals.com\/es\/wp-json\/wp\/v2\/pages\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosesrentals.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rosesrentals.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/es\/wp-json\/wp\/v2\/comments?post=70"}],"version-history":[{"count":64,"href":"https:\/\/www.rosesrentals.com\/es\/wp-json\/wp\/v2\/pages\/70\/revisions"}],"predecessor-version":[{"id":4312,"href":"https:\/\/www.rosesrentals.com\/es\/wp-json\/wp\/v2\/pages\/70\/revisions\/4312"}],"wp:attachment":[{"href":"https:\/\/www.rosesrentals.com\/es\/wp-json\/wp\/v2\/media?parent=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}