{"id":2088,"date":"2026-03-02T15:09:35","date_gmt":"2026-03-02T15:09:35","guid":{"rendered":"https:\/\/www.rosesrentals.com\/?p=2088"},"modified":"2026-05-10T09:00:32","modified_gmt":"2026-05-10T09:00:32","slug":"visit-cadaques-from-roses","status":"publish","type":"post","link":"https:\/\/www.rosesrentals.com\/en\/visiter-cadaques-depuis-roses\/","title":{"rendered":"Visiting Cadaqu\u00e9s from Roses: A Complete Guide"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2088\" class=\"elementor elementor-2088\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dbd17df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbd17df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-efc1b7b\" data-id=\"efc1b7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9833e15 elementor-widget elementor-widget-text-editor\" data-id=\"9833e15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cadaqu\u00e9s est sans doute le village le plus embl\u00e9matique de la Costa Brava. Ses maisons blanches immacul\u00e9es, ses ruelles fleuries, ses criques aux eaux turquoise et son lien ind\u00e9fectible avec Salvador Dal\u00ed en font une destination incontournable lors de tout s\u00e9jour \u00e0 Rosas. Et bonne nouvelle : depuis notre <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/appartement-vue-mer-roses-terrasse\/\">appartement terrasse panoramique<\/a> ou notre <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/appartement-renove-roses-canyelles\/\">appartement r\u00e9nov\u00e9 de Canyelles Petites<\/a>, Cadaqu\u00e9s est \u00e0 30 minutes de voiture. Voici tout ce qu&rsquo;il faut savoir pour visiter Cadaqu\u00e9s depuis Roses.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9aa73df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9aa73df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a885ca9\" data-id=\"a885ca9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd4323a elementor-widget elementor-widget-heading\" data-id=\"dd4323a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\ud83d\udccd Roses \u2192 Cadaqu\u00e9s : combien de temps ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f802e0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f802e0e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-466498c\" data-id=\"466498c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4d01ea elementor-widget elementor-widget-text-editor\" data-id=\"a4d01ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La distance en voiture entre Roses et Cadaqu\u00e9s est d&rsquo;environ 18 km pour un trajet d&rsquo;environ 21 minutes. C&rsquo;est court, mais la route est spectaculaire : elle serpente \u00e0 flanc de montagne \u00e0 travers le parc naturel du Cap de Creus, avec des vues \u00e0 couper le souffle sur la baie de Roses et la M\u00e9diterran\u00e9e.<\/p><blockquote class=\"ml-2 border-l-4 border-border-300\/10 pl-4 text-text-300\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u26a0\ufe0f <strong>Attention :<\/strong> La route est \u00e9troite et sinueuse, avec de nombreux virages. Conduisez prudemment et profitez du paysage !<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51b30b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51b30b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b948f4\" data-id=\"5b948f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7cf13e elementor-widget elementor-widget-heading\" data-id=\"b7cf13e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment aller \u00e0 Cadaqu\u00e9s depuis Roses ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b8cab4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b8cab4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87bc9ea\" data-id=\"87bc9ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0eb8f8c elementor-widget elementor-widget-heading\" data-id=\"0eb8f8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">En voiture - Le plus rapide<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1afa435 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1afa435\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be29471\" data-id=\"be29471\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50fea05 elementor-widget elementor-widget-text-editor\" data-id=\"50fea05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">La voiture est le moyen le plus pratique pour visiter Cadaqu\u00e9s depuis Roses, avec un trajet d&rsquo;environ 21 minutes.<\/p><blockquote class=\"ml-2 border-l-4 border-border-300\/10 pl-4 text-text-300\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f4a1.svg\" alt=\"\ud83d\udca1\" \/> <strong>Conseil stationnement :<\/strong> En haute saison, il est pratiquement impossible de se garer gratuitement \u00e0 Cadaqu\u00e9s, car les quelques places publiques sont r\u00e9serv\u00e9es aux r\u00e9sidents.\u00a0Garez-vous au parking payant \u00e0 l&rsquo;entr\u00e9e du village et continuez \u00e0 pied \u2014 c&rsquo;est de toute fa\u00e7on la meilleure fa\u00e7on de d\u00e9couvrir ses ruelles.<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-271ef25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"271ef25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e575190\" data-id=\"e575190\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0058a8f elementor-widget elementor-widget-heading\" data-id=\"0058a8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">En bus - Sans voiture<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3653d9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3653d9b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6b5d64\" data-id=\"e6b5d64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b092609 elementor-widget elementor-widget-text-editor\" data-id=\"b092609\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La compagnie Sarfa propose des bus directs entre Roses et Cadaqu\u00e9s, avec des trajets directs en 28 minutes environ. C&rsquo;est une excellente option pour \u00e9viter le stress du stationnement.<\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\"><strong>Compagnie :<\/strong> Moventis Sarfa<\/li><li class=\"whitespace-normal break-words pl-2\"><strong>Tarif :<\/strong> \u00e0 partir de 3\u20ac<\/li><li class=\"whitespace-normal break-words pl-2\"><strong>Horaires :<\/strong> <a href=\"https:\/\/compras.moventis.es\/online\/search\" target=\"_blank\" rel=\"noopener\"><code class=\"bg-text-200\/5 border border-0.5 border-border-300 text-danger-000 whitespace-pre-wrap rounded-[0.4rem] px-1 py-px text-[0.9rem]\">moventis<\/code><\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cff72f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cff72f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50646e6\" data-id=\"50646e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d3c8b9 elementor-widget elementor-widget-heading\" data-id=\"4d3c8b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00c0 v\u00e9lo - Pour les sportifs<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc7a460 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc7a460\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f37344\" data-id=\"0f37344\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3d9069 elementor-widget elementor-widget-text-editor\" data-id=\"d3d9069\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La route entre Roses et Cadaqu\u00e9s est praticable \u00e0 v\u00e9lo, avec un trajet aller-retour d&rsquo;environ 38 km et 580 m\u00e8tres de d\u00e9nivel\u00e9 positif, pour environ 1h \u00e0 1h15 dans chaque sens. R\u00e9serv\u00e9 aux cyclistes en bonne condition physique !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1051f5f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1051f5f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b059b4\" data-id=\"7b059b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a02989 elementor-widget elementor-widget-heading\" data-id=\"4a02989\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">En bateau - L'option la plus romantique<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82138ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82138ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-654a63c\" data-id=\"654a63c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5e8bc9 elementor-widget elementor-widget-text-editor\" data-id=\"b5e8bc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">L&rsquo;\u00e9t\u00e9, des liaisons maritimes relient Roses \u00e0 Cadaqu\u00e9s, et arriver par la mer est une exp\u00e9rience particuli\u00e8rement agr\u00e9able.\u00a0Renseignez-vous au port de Roses en saison.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a53c108 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a53c108\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b62be76\" data-id=\"b62be76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa5b357 elementor-widget elementor-widget-heading\" data-id=\"aa5b357\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\ud83c\udfa8 Que voir \u00e0 Cadaqu\u00e9s ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8625370 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8625370\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5a29b9\" data-id=\"f5a29b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f33d53c elementor-widget elementor-widget-heading\" data-id=\"f33d53c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">1. La Maison-Mus\u00e9e Salvador Dal\u00ed \u00e0 Portlligat \u2b50<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65edc37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65edc37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5058721\" data-id=\"5058721\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80610de elementor-widget elementor-widget-text-editor\" data-id=\"80610de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">C&rsquo;est le clou du spectacle. Portlligat est tr\u00e8s connue car elle a \u00e9t\u00e9 le lieu de r\u00e9sidence de Salvador Dal\u00ed pendant plusieurs ann\u00e9es. Vous y trouverez un petit port de p\u00eacheurs et une baie bien pr\u00e9serv\u00e9e, ainsi que la Maison-Mus\u00e9e du peintre.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La maison-mus\u00e9e est compos\u00e9e d&rsquo;une s\u00e9rie de cabanes de p\u00eacheurs structur\u00e9es de mani\u00e8re labyrinthique. Vous pouvez y visiter l&rsquo;atelier du peintre, la biblioth\u00e8que, les chambres et le jardin, rempli de sculptures surr\u00e9alistes.<\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\"><strong>Tarif :<\/strong> 15\u20ac plein tarif, 12\u20ac tarif r\u00e9duit<\/li><li class=\"whitespace-normal break-words pl-2\"><strong>R\u00e9servation obligatoire<\/strong> \u2014 le site affiche souvent complet, r\u00e9servez \u00e0 l&rsquo;avance<\/li><li class=\"whitespace-normal break-words pl-2\"><strong>R\u00e9servations :<\/strong> <a href=\"https:\/\/www.salvador-dali.org\" target=\"_blank\" rel=\"noopener\"><code class=\"bg-text-200\/5 border border-0.5 border-border-300 text-danger-000 whitespace-pre-wrap rounded-[0.4rem] px-1 py-px text-[0.9rem]\">salvador-dali<\/code><\/a><\/li><\/ul><blockquote class=\"ml-2 border-l-4 border-border-300\/10 pl-4 text-text-300\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u26a0\ufe0f Portlligat se trouve \u00e0 1 km au nord du centre de Cadaqu\u00e9s, soit environ 20 minutes \u00e0 pied.<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1085241 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1085241\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e41eb3\" data-id=\"1e41eb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2098b6b elementor-widget elementor-widget-heading\" data-id=\"2098b6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">2. Les ruelles blanches du centre historique<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1578fca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1578fca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-713cbde\" data-id=\"713cbde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-301e4cc elementor-widget elementor-widget-text-editor\" data-id=\"301e4cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La vieille muraille de Cadaqu\u00e9s et l&rsquo;incontournable promenade du front de mer sont des visites \u00e0 ne pas manquer. Perdez-vous dans les ruelles pav\u00e9es, admirez les maisons blanchies \u00e0 la chaux couvertes de bougainvilliers et faites une pause dans l&rsquo;une des terrasses donnant sur la mer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e5b9db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e5b9db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-240585a\" data-id=\"240585a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7608441 elementor-widget elementor-widget-heading\" data-id=\"7608441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">3. L'\u00e9glise de Santa Maria<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ecdccc5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ecdccc5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b996e4\" data-id=\"3b996e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-626710f elementor-widget elementor-widget-text-editor\" data-id=\"626710f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">L&rsquo;\u00e9glise de Santa Maria est une construction de grande valeur architecturale, \u00e9difi\u00e9e pour remplacer la pr\u00e9c\u00e9dente, d\u00e9truite par le pirate Barberousse. Elle domine le village depuis son promontoire et offre une vue magnifique sur la baie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9ee0ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9ee0ee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74c90ae\" data-id=\"74c90ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-857123d elementor-widget elementor-widget-heading\" data-id=\"857123d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">4. Les criques sauvages aux alentours<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97ac892 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97ac892\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c27027\" data-id=\"8c27027\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71e3a0d elementor-widget elementor-widget-text-editor\" data-id=\"71e3a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cadaqu\u00e9s est entour\u00e9e de criques d&rsquo;une beaut\u00e9 sauvage, accessibles \u00e0 pied ou en kayak. Le parc naturel du Cap de Creus, qui englobe Cadaqu\u00e9s, est l&rsquo;un des plus impressionnants de la p\u00e9ninsule ib\u00e9rique, avec plus de 13 800 hectares de nature pr\u00e9serv\u00e9e o\u00f9 randonn\u00e9es, promenades et baignades sont au programme.<\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\"><strong>Informations officielles :<\/strong> <a href=\"https:\/\/parcsnaturals.gencat.cat\/fr\/cap-de-creus\" target=\"_blank\" rel=\"noopener\"><code class=\"bg-text-200\/5 border border-0.5 border-border-300 text-danger-000 whitespace-pre-wrap rounded-[0.4rem] px-1 py-px text-[0.9rem]\">cap-de-creus<\/code><\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3fcf85 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3fcf85\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aba15f4\" data-id=\"aba15f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68a4883 elementor-widget elementor-widget-heading\" data-id=\"68a4883\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">5. Le Mus\u00e9e Th\u00e9\u00e2tre Dal\u00ed de Figueres, en bonus<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52e7e41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52e7e41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2e7c42\" data-id=\"d2e7c42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d98cfc elementor-widget elementor-widget-text-editor\" data-id=\"2d98cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Si vous souhaitez prolonger votre journ\u00e9e, Figueres n&rsquo;est qu&rsquo;\u00e0 30 minutes de Cadaqu\u00e9s. Le Th\u00e9\u00e2tre-Mus\u00e9e Dal\u00ed de Figueres est un site unique au monde, un mus\u00e9e-th\u00e9\u00e2tre compl\u00e8tement d\u00e9lirant que Dal\u00ed a \u00e9difi\u00e9 \u00e0 sa propre gloire, transformant l&rsquo;ancien th\u00e9\u00e2tre de la ville en une sorte de ch\u00e2teau kitsch aux murs roses, coiff\u00e9 d&rsquo;\u0153ufs.<\/p><ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\"><li class=\"whitespace-normal break-words pl-2\"><strong>R\u00e9servations :<\/strong> <a href=\"https:\/\/www.salvador-dali.org\" target=\"_blank\" rel=\"noopener\"><code class=\"bg-text-200\/5 border border-0.5 border-border-300 text-danger-000 whitespace-pre-wrap rounded-[0.4rem] px-1 py-px text-[0.9rem]\">salvador-dali<\/code><\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0b33bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0b33bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf5b933\" data-id=\"cf5b933\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb8f38c elementor-widget elementor-widget-heading\" data-id=\"cb8f38c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\ud83c\udf7d\ufe0f O\u00f9 d\u00e9jeuner \u00e0 Cadaqu\u00e9s ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f206d94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f206d94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b2f374\" data-id=\"2b2f374\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97a520e elementor-widget elementor-widget-text-editor\" data-id=\"97a520e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Cadaqu\u00e9s est r\u00e9put\u00e9e pour sa gastronomie, notamment ses poissons et fruits de mer fra\u00eechement p\u00each\u00e9s. Profitez d&rsquo;une pause d\u00e9jeuner sur une terrasse du front de mer \u2014 les restaurants autour de la Pla\u00e7a de la Palmera sont particuli\u00e8rement bien situ\u00e9s avec vue sur la baie.<\/p><blockquote class=\"ml-2 border-l-4 border-border-300\/10 pl-4 text-text-300\"><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udca1 R\u00e9servez votre table \u00e0 l&rsquo;avance en juillet-ao\u00fbt &#8211; les terrasses sont tr\u00e8s pris\u00e9es et se remplissent rapidement.<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13b543e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13b543e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e719e73\" data-id=\"e719e73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e90107 elementor-widget elementor-widget-heading\" data-id=\"1e90107\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u23f0 Combien de temps pr\u00e9voir ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b36358f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b36358f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2898494\" data-id=\"2898494\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab4c0ec elementor-widget elementor-widget-text-editor\" data-id=\"ab4c0ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table class=\"min-w-full border-collapse text-sm leading-[1.7] whitespace-normal\"><thead class=\"text-left\"><tr><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Dur\u00e9e<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Programme<\/th><\/tr><\/thead><tbody><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\"><strong>Demi-journ\u00e9e<\/strong><\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Visite du village, promenade, baignade dans une crique<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\"><strong>Journ\u00e9e compl\u00e8te<\/strong><\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Village + Maison Dal\u00ed \u00e0 Portlligat + d\u00e9jeuner en terrasse<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\"><strong>Journ\u00e9e + Figueres<\/strong><\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Village + Maison Dal\u00ed + Mus\u00e9e Th\u00e9\u00e2tre Dal\u00ed de Figueres<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ab9540 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ab9540\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e9c10b\" data-id=\"5e9c10b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32c1949 elementor-widget elementor-widget-heading\" data-id=\"32c1949\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\ud83d\uddfa\ufe0f Comment aller \u00e0 Cadaqu\u00e9s depuis Roses - R\u00e9capitulatif<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f176782 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f176782\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5f291d\" data-id=\"c5f291d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5abee2 elementor-widget elementor-widget-text-editor\" data-id=\"a5abee2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"overflow-x-auto w-full px-2 mb-6\"><table class=\"min-w-full border-collapse text-sm leading-[1.7] whitespace-normal\"><thead class=\"text-left\"><tr><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Moyen de transport<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Dur\u00e9e<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Prix indicatif<\/th><th class=\"text-text-100 border-b-0.5 border-border-300\/60 py-2 pr-4 align-top font-bold\" scope=\"col\">Id\u00e9al pour<\/th><\/tr><\/thead><tbody><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">\ud83d\ude97 Voiture<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">~21 min<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">3-5\u20ac carburant<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Familles, libert\u00e9, bagages<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">\ud83d\ude8c Bus Sarfa<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">~28 min<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">\u00e0 partir de 3\u20ac<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Sans voiture, budget serr\u00e9<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">\ud83d\udea3 Kayak<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">~2h (aller)<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">20-40\u20ac location<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Sportifs, aventure<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">\u26f5 Bateau<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">~45 min<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Variable (saison)<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Romantique, exp\u00e9rience unique<\/td><\/tr><tr><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">\ud83d\udeb4 V\u00e9lo<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">~1h-1h15 (aller)<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Gratuit \/ location<\/td><td class=\"border-b-0.5 border-border-300\/30 py-2 pr-4 align-top\">Cyclistes confirm\u00e9s<\/td><\/tr><\/tbody><\/table><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5907360 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5907360\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d735fbf\" data-id=\"d735fbf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ec13b1 elementor-widget elementor-widget-heading\" data-id=\"7ec13b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\ud83d\udca1 Nos conseils pratiques<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed5e448 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed5e448\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0575317\" data-id=\"0575317\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c605de elementor-widget elementor-widget-text-editor\" data-id=\"7c605de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><a href=\"https:\/\/www.rosesrentals.com\/comment-venir-a-roses\/\"><strong>Quand y aller ?<\/strong><\/a> Privil\u00e9giez un d\u00e9part matinal (avant 9h) en juillet-ao\u00fbt pour visiter le village au calme avant l&rsquo;afflux des touristes. Il est recommand\u00e9 de visiter t\u00f4t le matin ou en fin d&rsquo;apr\u00e8s-midi pour \u00e9viter la foule, et les semaines hors saison offrent une tranquillit\u00e9 tr\u00e8s appr\u00e9ciable.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>La Maison Dal\u00ed :<\/strong> R\u00e9servez imp\u00e9rativement en ligne avant votre visite \u2014 les cr\u00e9neaux partent tr\u00e8s rapidement en haute saison.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Avec des enfants :<\/strong> La visite du village et des criques convient parfaitement aux enfants. La Maison Dal\u00ed est accessible d\u00e8s 8-10 ans, mais les plus jeunes peuvent s&rsquo;y ennuyer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4108cd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4108cd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a9a0fc0\" data-id=\"a9a0fc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-418102c elementor-widget elementor-widget-heading\" data-id=\"418102c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Profitez de Cadaqu\u00e9s depuis nos appartements \u00e0 Roses<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e983ce3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e983ce3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c134497\" data-id=\"c134497\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95d6c2f elementor-widget elementor-widget-text-editor\" data-id=\"95d6c2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos appartements sont id\u00e9alement situ\u00e9s pour rayonner vers Cadaqu\u00e9s et toutes les merveilles de la Costa Brava. \u00c0 seulement 21 minutes en voiture de votre location de vacances \u00e0 Rosas, vous pouvez visiter Cadaqu\u00e9s le matin et profiter de la plage de Roses l&rsquo;apr\u00e8s-midi !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cadaqu\u00e9s est sans doute le village le plus embl\u00e9matique de la Costa Brava. Ses maisons blanches immacul\u00e9es, ses ruelles fleuries, ses criques aux eaux turquoise et son lien ind\u00e9fectible avec Salvador Dal\u00ed en font une destination incontournable lors de tout s\u00e9jour \u00e0 Rosas. Et bonne nouvelle : depuis notre appartement terrasse panoramique ou notre appartement [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3622,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-excursions-depuis-roses"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Visiter Cadaqu\u00e9s depuis Roses : guide complet | Roses Rentals<\/title>\n<meta name=\"description\" content=\"Comment aller visiter Cadaqu\u00e9s depuis Roses, que voir, que faire ? Maison Dal\u00ed, ruelles blanches, criques sauvages\u2026 Notre guide complet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosesrentals.com\/en\/visit-cadaques-from-roses\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visiter Cadaqu\u00e9s depuis Roses : guide complet\" \/>\n<meta property=\"og:description\" content=\"Comment aller visiter Cadaqu\u00e9s depuis Roses, que voir, que faire ? Maison Dal\u00ed, ruelles blanches, criques sauvages\u2026 Notre guide complet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosesrentals.com\/en\/visit-cadaques-from-roses\/\" \/>\n<meta property=\"og:site_name\" content=\"Roses Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-02T15:09:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T09:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/03\/que-ver-en-cadaques-en-un-dia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Philippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/\",\"name\":\"Visiter Cadaqu\u00e9s depuis Roses : guide complet | Roses Rentals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/que-ver-en-cadaques-en-un-dia.png\",\"datePublished\":\"2026-03-02T15:09:35+00:00\",\"dateModified\":\"2026-05-10T09:00:32+00:00\",\"description\":\"Comment aller visiter Cadaqu\u00e9s depuis Roses, que voir, que faire ? Maison Dal\u00ed, ruelles blanches, criques sauvages\u2026 Notre guide complet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/que-ver-en-cadaques-en-un-dia.png\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/que-ver-en-cadaques-en-un-dia.png\",\"width\":1024,\"height\":576,\"caption\":\"visiter cadaqu\u00e8s depuis roses\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rosesrentals.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visiter Cadaqu\u00e9s depuis Roses : guide complet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"name\":\"rosesrentals.com\",\"description\":\"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rosesrentals.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\",\"name\":\"roses Rentals\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rosesrentals\",\"https:\\\/\\\/www.instagram.com\\\/rosesrentals\"],\"description\":\"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.\",\"telephone\":[],\"openingHoursSpecification\":[]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/visiter-cadaques-depuis-roses\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"width\":150,\"height\":150,\"caption\":\"roses Rentals\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Visiting Cadaqu\u00e9s from Roses: a complete guide | Roses Rentals","description":"How to visit Cadaqu\u00e9s from Roses, what to see, what to do? Dal\u00ed House, white alleyways, wild coves\u2026 Our complete guide.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosesrentals.com\/en\/visit-cadaques-from-roses\/","og_locale":"en_GB","og_type":"article","og_title":"Visiter Cadaqu\u00e9s depuis Roses : guide complet","og_description":"Comment aller visiter Cadaqu\u00e9s depuis Roses, que voir, que faire ? Maison Dal\u00ed, ruelles blanches, criques sauvages\u2026 Notre guide complet.","og_url":"https:\/\/www.rosesrentals.com\/en\/visit-cadaques-from-roses\/","og_site_name":"Roses Rentals","article_publisher":"https:\/\/www.facebook.com\/rosesrentals","article_author":"https:\/\/www.facebook.com\/rosesrentals","article_published_time":"2026-03-02T15:09:35+00:00","article_modified_time":"2026-05-10T09:00:32+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/03\/que-ver-en-cadaques-en-un-dia.png","type":"image\/png"}],"author":"Philippe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/","url":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/","name":"Visiting Cadaqu\u00e9s from Roses: a complete guide | Roses Rentals","isPartOf":{"@id":"https:\/\/www.rosesrentals.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/#primaryimage"},"image":{"@id":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/03\/que-ver-en-cadaques-en-un-dia.png","datePublished":"2026-03-02T15:09:35+00:00","dateModified":"2026-05-10T09:00:32+00:00","description":"How to visit Cadaqu\u00e9s from Roses, what to see, what to do? Dal\u00ed House, white alleyways, wild coves\u2026 Our complete guide.","breadcrumb":{"@id":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/#primaryimage","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/03\/que-ver-en-cadaques-en-un-dia.png","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/03\/que-ver-en-cadaques-en-un-dia.png","width":1024,"height":576,"caption":"visiter cadaqu\u00e8s depuis roses"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rosesrentals.com\/"},{"@type":"ListItem","position":2,"name":"Visiter Cadaqu\u00e9s depuis Roses : guide complet"}]},{"@type":"WebSite","@id":"https:\/\/www.rosesrentals.com\/#website","url":"https:\/\/www.rosesrentals.com\/","name":"rosesrentals.com","description":"Holiday rentals Roses Costa Brava | Sea view apartments - Roses Rentals","publisher":{"@id":"https:\/\/www.rosesrentals.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosesrentals.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Organization","Place"],"@id":"https:\/\/www.rosesrentals.com\/#organization","name":"Roses Rentals","url":"https:\/\/www.rosesrentals.com\/","logo":{"@id":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/rosesrentals","https:\/\/www.instagram.com\/rosesrentals"],"description":"Roses Rentals is a direct holiday rental offering two sea-view apartments in Roses, on the Costa Brava in Catalonia, Spain. Located in the residential area of Canyelles Petites, a two-minute walk from the beach, our apartments accommodate up to 4 people in a calm and authentic setting. Sea-view terraces, parking included, self check-in. Direct booking without platform fees, best prices guaranteed. Ideal for family or couple holidays on the Costa Brava.","telephone":[],"openingHoursSpecification":[]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/#local-main-organization-logo","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","width":150,"height":150,"caption":"roses Rentals"}]}},"_links":{"self":[{"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/posts\/2088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/comments?post=2088"}],"version-history":[{"count":46,"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/posts\/2088\/revisions"}],"predecessor-version":[{"id":3784,"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/posts\/2088\/revisions\/3784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/media\/3622"}],"wp:attachment":[{"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/media?parent=2088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/categories?post=2088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosesrentals.com\/en\/wp-json\/wp\/v2\/tags?post=2088"}],"curies":[{"name":"wordpress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}