{"id":3537,"date":"2026-04-17T12:44:53","date_gmt":"2026-04-17T12:44:53","guid":{"rendered":"https:\/\/www.rosesrentals.com\/?p=3537"},"modified":"2026-05-12T14:27:33","modified_gmt":"2026-05-12T14:27:33","slug":"mittelalterliche-dorfer-an-der-costa-brava-roses","status":"publish","type":"post","link":"https:\/\/www.rosesrentals.com\/de\/villages-medievaux-costa-brava-roses\/","title":{"rendered":"Mittelalterliche D\u00f6rfer von Roses aus besuchen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3537\" class=\"elementor elementor-3537\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dbd17df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbd17df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-efc1b7b\" data-id=\"efc1b7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9833e15 elementor-widget elementor-widget-text-editor\" data-id=\"9833e15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La Costa Brava, ce n&rsquo;est pas que la mer. \u00c0 quelques kilom\u00e8tres de la <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/plages-roses-costa-brava\/\">plage de Canyelles Petites<\/a>, l&rsquo;arri\u00e8re-pays de la province de G\u00e9rone rec\u00e8le quelques-uns des villages m\u00e9di\u00e9vaux les mieux conserv\u00e9s de la Costa Brava en Espagne. Ruelles pav\u00e9es, maisons en pierre dor\u00e9e, ch\u00e2teaux perch\u00e9s et places ombrag\u00e9es : un voyage dans le temps \u00e0 port\u00e9e de voiture depuis nos <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/nos-appartements\/\">appartements \u00e0 Rosas<\/a>. Voici notre s\u00e9lection de six villages incontournables, tous accessibles en moins d&rsquo;une heure.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea63ea3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea63ea3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59041c0\" data-id=\"59041c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0010a8d elementor-widget elementor-widget-heading\" data-id=\"0010a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Peralada : le village des vins et du festival (20 min)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca2c546 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca2c546\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f42f5d4\" data-id=\"f42f5d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-913e9f5 elementor-widget elementor-widget-text-editor\" data-id=\"913e9f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Peralada est le village m\u00e9di\u00e9val le plus proche de Roses, et sans doute le plus facile \u00e0 combiner avec une journ\u00e9e de plage. Nich\u00e9 au c\u0153ur des vignes de l&rsquo;appellation d&rsquo;origine Empord\u00e0, il s\u00e9duit d\u00e8s l&rsquo;entr\u00e9e par ses remparts du XIVe si\u00e8cle et son ch\u00e2teau imposant qui domine le village.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Le ch\u00e2teau de Peralada est aujourd&rsquo;hui un h\u00f4tel de luxe, un casino et le cadre du c\u00e9l\u00e8bre Festival Internacional de M\u00fasica de Peralada, l&rsquo;un des festivals d&rsquo;op\u00e9ra et de musique classique les plus prestigieux d&rsquo;Europe, qui se tient chaque \u00e9t\u00e9 dans ses jardins. Si vous s\u00e9journez \u00e0 Roses en juillet ou ao\u00fbt, consultez la programmation. Une soir\u00e9e au festival est une exp\u00e9rience inoubliable.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Promenez-vous dans les ruelles du centre historique, visitez le clo\u00eetre Sant Dom\u00e8nech et l&rsquo;\u00e9glise Sant Mart\u00ed, puis terminez par une d\u00e9gustation dans l&rsquo;une des caves du domaine. Les vins de l&rsquo;Empord\u00e0 m\u00e9ritent amplement le d\u00e9tour. Vous en trouverez d&rsquo;ailleurs une belle s\u00e9lection dans les <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/ou-faire-ses-courses-a-roses-marches-supermarches-et-bonnes-adresses\/\">boutiques et march\u00e9s de Roses<\/a>.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udccd <a href=\"https:\/\/www.visitperalada.cat\/fr\/\" target=\"_blank\" rel=\"noopener\">Peralada<\/a>, Alt Empord\u00e0 &#8211; 20 min depuis Roses<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffb1a01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffb1a01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aabab45\" data-id=\"aabab45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11b43f6 elementor-widget elementor-widget-heading\" data-id=\"11b43f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Castell\u00f3 d'Emp\u00faries : la cath\u00e9drale de l'Empord\u00e0 (25 min)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-657ff26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"657ff26\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec26d4a\" data-id=\"ec26d4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c6fa7c elementor-widget elementor-widget-text-editor\" data-id=\"7c6fa7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Castell\u00f3 d&rsquo;Emp\u00faries est souvent ignor\u00e9e des touristes press\u00e9s qui passent \u00e0 c\u00f4t\u00e9 en rejoignant Empuriabrava. C&rsquo;est une erreur. Cette ancienne capitale du comt\u00e9 d&rsquo;Emp\u00faries abrite l&rsquo;une des plus belles basiliques gothiques de Catalogne (Santa Maria, surnomm\u00e9e \u00ab\u00a0la cath\u00e9drale de l&rsquo;Empord\u00e0\u00a0\u00bb) dont le clocher monumental domine la plaine depuis des si\u00e8cles.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Le centre historique est remarquablement pr\u00e9serv\u00e9. Ses ruelles m\u00e9di\u00e9vales, ses places tranquilles, ses portails en pierre et ses anciennes demeures seigneuriales invitent \u00e0 une promenade sans itin\u00e9raire pr\u00e9cis. Chaque recoin r\u00e9serve une surprise architecturale. Le march\u00e9 hebdomadaire, qui se tient le lundi matin, est un excellent pr\u00e9texte pour s&rsquo;impr\u00e9gner de la vie locale.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udccd <a href=\"https:\/\/costabrava.org\/fr\/ou-se-rendre\/regions\/alt-emporda\/castello-dempuries\/\" target=\"_blank\" rel=\"noopener\">Castell\u00f3 d&rsquo;Emp\u00faries<\/a>, Alt Empord\u00e0 &#8211; 25 min depuis Roses<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9e6110 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9e6110\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ee4b30\" data-id=\"1ee4b30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fbcad8 elementor-widget elementor-widget-heading\" data-id=\"8fbcad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Besal\u00fa : le joyau m\u00e9di\u00e9val de la Garrotxa (55 min)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23010e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23010e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0437eb1\" data-id=\"0437eb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4113c81 elementor-widget elementor-widget-text-editor\" data-id=\"4113c81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Besal\u00fa est sans doute le village m\u00e9di\u00e9val le plus spectaculaire de toute la province de G\u00e9rone. Situ\u00e9 \u00e0 la porte du parc naturel de la Zone Volcanique de la Garrotxa, il est travers\u00e9 par la rivi\u00e8re Fluvi\u00e0 et domin\u00e9 par son pont fortifi\u00e9 du XIIe si\u00e8cle \u2014 l&rsquo;une des images les plus photographi\u00e9es de Catalogne.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Franchir ce pont \u00e0 sept arches, c&rsquo;est entrer de plain-pied dans le Moyen \u00c2ge. Le noyau historique de Besal\u00fa a \u00e9t\u00e9 d\u00e9clar\u00e9 Patrimoine Historique et Artistique National. On y d\u00e9couvre le monast\u00e8re Sant Pere, les bains juifs souterrains (miqv\u00e9), l&rsquo;un des rares exemples conserv\u00e9s en Europe,\u00a0 la Curie royale et d&rsquo;innombrables fa\u00e7ades en pierre qui racontent dix si\u00e8cles d&rsquo;histoire.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Comptez une demi-journ\u00e9e pour profiter pleinement de Besal\u00fa, et terminez par un repas dans l&rsquo;un des restaurants de la place centrale. La gastronomie locale est \u00e0 la hauteur du site.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udccd <a href=\"https:\/\/www.visitbesalu.com\/\" target=\"_blank\" rel=\"noopener\">Besal\u00fa<\/a>, La Garrotxa &#8211; 55 min depuis Roses<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f74eeba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f74eeba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c904a99\" data-id=\"c904a99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73bcfbb elementor-widget elementor-widget-heading\" data-id=\"73bcfbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pals : la cit\u00e9 dor\u00e9e perch\u00e9e sur sa colline (55 min)\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf7b3df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf7b3df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0ea0ee\" data-id=\"c0ea0ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f690d87 elementor-widget elementor-widget-text-editor\" data-id=\"f690d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Pals est souvent d\u00e9sign\u00e9 comme le village m\u00e9di\u00e9val le mieux restaur\u00e9 de la Costa Brava, et la r\u00e9putation est m\u00e9rit\u00e9e. Perch\u00e9 sur une colline qui offre des panoramas \u00e0 couper le souffle sur la plaine de l&rsquo;Empord\u00e0, la mer M\u00e9diterran\u00e9e et les \u00eeles Medes, le village a re\u00e7u le Prix des Beaux-Arts en 1973 pour la qualit\u00e9 de sa restauration.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">On entre dans Pals par une porte en pierre, on grimpe dans les ruelles pav\u00e9es bord\u00e9es de maisons en pierre dor\u00e9e, et on se retrouve soudainement face \u00e0 la Tour de les Hores, la tour m\u00e9di\u00e9vale qui domine le village et depuis laquelle la vue est exceptionnelle. Les artisans, les galeries d&rsquo;art et les terrasses ombrag\u00e9es donnent \u00e0 Pals une atmosph\u00e8re vivante et chaleureuse, loin du village-mus\u00e9e fig\u00e9 dans le temps.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Aux alentours, la plaine agricole est c\u00e9l\u00e8bre pour ses rizi\u00e8res, un paysage inattendu \u00e0 quelques kilom\u00e8tres de la M\u00e9diterran\u00e9e.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udccd <a href=\"https:\/\/www.visitpals.com\/fr\/\" target=\"_blank\" rel=\"noopener\">Pals<\/a>, Baix Empord\u00e0 &#8211; 55 min depuis Roses<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1aa83d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1aa83d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e3217b\" data-id=\"5e3217b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c79e06 elementor-widget elementor-widget-heading\" data-id=\"3c79e06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Peratallada : le labyrinthe de pierre taill\u00e9e (60 min)\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4776fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4776fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d57351\" data-id=\"8d57351\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3da67d8 elementor-widget elementor-widget-text-editor\" data-id=\"3da67d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Si vous ne devez visiter qu&rsquo;un seul village m\u00e9di\u00e9val de la Costa Brava, choisissez Peratallada. Son nom signifie litt\u00e9ralement \u00ab\u00a0pierre taill\u00e9e\u00a0\u00bb. Une r\u00e9f\u00e9rence aux douves creus\u00e9es dans le roc qui entourent encore le village. Class\u00e9 parmi les plus beaux villages de Catalogne, Peratallada est un labyrinthe de ruelles m\u00e9di\u00e9vales dont certaines gardent encore les traces des orni\u00e8res des charrettes dans le sol de pierre.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Le ch\u00e2teau du XIIe si\u00e8cle, la Plaza de les Voltes avec ses arcades et ses restaurants en terrasse, et l&rsquo;atmosph\u00e8re g\u00e9n\u00e9rale du village cr\u00e9ent une ambiance v\u00e9ritablement envo\u00fbtante. Peratallada est aussi r\u00e9put\u00e9 pour sa gastronomie, plusieurs tables de qualit\u00e9 y proposant une cuisine catalane authentique dans des cadres m\u00e9di\u00e9vaux magnifiques. Id\u00e9alement, combinez la visite avec Pals tout proche pour une journ\u00e9e villages m\u00e9di\u00e9vaux en boucle.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udccd <a href=\"https:\/\/www.visitperalada.cat\/fr\/\" target=\"_blank\" rel=\"noopener\">Peratallada<\/a>, Baix Empord\u00e0 &#8211; 60 min depuis Roses<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6e1d61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6e1d61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad4d96f\" data-id=\"ad4d96f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26e87c8 elementor-widget elementor-widget-heading\" data-id=\"26e87c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Monells : la place secr\u00e8te (60 min)\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-016039e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"016039e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36134f3\" data-id=\"36134f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5ed238 elementor-widget elementor-widget-text-editor\" data-id=\"c5ed238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Moins connu que ses voisins, Monells est une p\u00e9pite confidentielle qui m\u00e9rite amplement le d\u00e9tour. Son tr\u00e9sor est sa Plaza Major, une place m\u00e9di\u00e9vale entour\u00e9e d&rsquo;arcades gothiques d&rsquo;une beaut\u00e9 saisissante, l&rsquo;une des plus belles places m\u00e9di\u00e9vales de Catalogne selon les sp\u00e9cialistes. Monells fait partie d&rsquo;une commune regroupant trois villages,\u00a0 Cru\u00eflles, Monells et Sant Sadurn\u00ed de l&rsquo;Heura, qui ont su pr\u00e9server leur patrimoine commun de fa\u00e7on remarquable.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La tranquillit\u00e9 qui r\u00e8gne \u00e0 Monells contraste agr\u00e9ablement avec l&rsquo;animation des villages plus touristiques. C&rsquo;est l&rsquo;adresse id\u00e9ale pour ceux qui cherchent l&rsquo;authenticit\u00e9 sans la foule, et qui souhaitent profiter d&rsquo;un caf\u00e9 en terrasse sur une place m\u00e9di\u00e9vale comme si le temps s&rsquo;\u00e9tait arr\u00eat\u00e9.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\ud83d\udccd <a href=\"https:\/\/catalunyaturisme.cat\/fr\/monells\/\" target=\"_blank\" rel=\"noopener\">Monells<\/a>, Baix Empord\u00e0 &#8211; 60 min depuis Roses<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15c673a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15c673a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f8d6b6\" data-id=\"5f8d6b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ddc0d1 elementor-widget elementor-widget-heading\" data-id=\"8ddc0d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment organiser votre journ\u00e9e ?\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fe48170 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe48170\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fdc0393\" data-id=\"fdc0393\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4da31ab elementor-widget elementor-widget-text-editor\" data-id=\"4da31ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ces six villages se combinent naturellement en circuits d&rsquo;une journ\u00e9e. Voici deux itin\u00e9raires possibles depuis votre location de vacances dans un de nos <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/nos-appartements\/\">appartements de Canyelles Petites<\/a> :<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Circuit Nord (demi-journ\u00e9e)<\/strong> : Peralada + Castell\u00f3 d&rsquo;Emp\u00faries &#8211; id\u00e9al en matin\u00e9e, retour \u00e0 la plage l&rsquo;apr\u00e8s-midi.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Circuit Sud (journ\u00e9e compl\u00e8te)<\/strong> : Pals + Peratallada + Monells &#8211; les trois villages sont tr\u00e8s proches les uns des autres et se visitent facilement dans la m\u00eame journ\u00e9e.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Journ\u00e9e Besal\u00fa<\/strong> : Combinez avec une visite du <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/visiter-cadaques-depuis-roses\/\">Mus\u00e9e Dal\u00ed de Figueres<\/a> en cours de route, en effet les deux sites sont proches l&rsquo;un de l&rsquo;autre.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Consultez notre <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.rosesrentals.com\/agenda-evenements-roses-costa-brava\/\">guide complet des activit\u00e9s \u00e0 Roses<\/a> et notre article sur les <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"\/10-choses-a-faire-a-roses\/\">10 choses \u00e0 faire \u00e0 Roses en famille<\/a> pour pr\u00e9parer votre s\u00e9jour sur la Costa Brava.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Costa Brava, ce n&rsquo;est pas que la mer. \u00c0 quelques kilom\u00e8tres de la plage de Canyelles Petites, l&rsquo;arri\u00e8re-pays de la province de G\u00e9rone rec\u00e8le quelques-uns des villages m\u00e9di\u00e9vaux les mieux conserv\u00e9s de la Costa Brava en Espagne. Ruelles pav\u00e9es, maisons en pierre dor\u00e9e, ch\u00e2teaux perch\u00e9s et places ombrag\u00e9es : un voyage dans le temps [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-3537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-excursions-depuis-roses"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Proche de Rosas : villages m\u00e9dievaux Costa Brava | Roses Rentals<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les plus beaux villages m\u00e9di\u00e9vaux de la Costa Brava, tous accessibles en moins d&#039;une heure depuis Roses.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosesrentals.com\/de\/mittelalterliche-dorfer-an-der-costa-brava-roses\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villages m\u00e9di\u00e9vaux \u00e0 visiter depuis Roses\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les plus beaux villages m\u00e9di\u00e9vaux de la Costa Brava, tous accessibles en moins d&#039;une heure depuis Roses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosesrentals.com\/de\/mittelalterliche-dorfer-an-der-costa-brava-roses\/\" \/>\n<meta property=\"og:site_name\" content=\"Roses Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rosesrentals\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T12:44:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T14:27:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/monells-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Philippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/\",\"name\":\"Proche de Rosas : villages m\u00e9dievaux Costa Brava | Roses Rentals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/monells-3.jpg\",\"datePublished\":\"2026-04-17T12:44:53+00:00\",\"dateModified\":\"2026-05-12T14:27:33+00:00\",\"description\":\"D\u00e9couvrez les plus beaux villages m\u00e9di\u00e9vaux de la Costa Brava, tous accessibles en moins d'une heure depuis Roses.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/monells-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/monells-3.jpg\",\"width\":888,\"height\":500,\"caption\":\"villages m\u00e9di\u00e9vaux Costa Brava\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rosesrentals.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villages m\u00e9di\u00e9vaux \u00e0 visiter depuis Roses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#website\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"name\":\"rosesrentals.com\",\"description\":\"Location vacances Roses Costa Brava | Appartements vue mer - Roses Rentals\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rosesrentals.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/#organization\",\"name\":\"roses Rentals\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rosesrentals\",\"https:\\\/\\\/www.instagram.com\\\/rosesrentals\"],\"description\":\"Roses Rentals est une location de vacances en direct proposant deux appartements vue mer \u00e0 Roses (Rosas), sur la Costa Brava en Catalogne, Espagne. Situ\u00e9s dans le quartier r\u00e9sidentiel de Canyelles Petites, \u00e0 deux minutes \u00e0 pied de la plage, nos appartements accueillent jusqu'\u00e0 4 personnes dans un cadre calme et authentique. Terrasses vue mer, parking inclus, check-in autonome. R\u00e9servation directe sans frais de plateforme, meilleurs prix garantis. Id\u00e9al pour des vacances en famille ou en couple sur la Costa Brava.\",\"telephone\":[],\"openingHoursSpecification\":[]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rosesrentals.com\\\/villages-medievaux-costa-brava-roses\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"contentUrl\":\"https:\\\/\\\/www.rosesrentals.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/rosesrentals.com_.png\",\"width\":150,\"height\":150,\"caption\":\"roses Rentals\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"In der N\u00e4he von Rosas: mittelalterliche D\u00f6rfer Costa Brava | Roses Rentals","description":"Entdecken Sie die sch\u00f6nsten mittelalterlichen D\u00f6rfer der Costa Brava, alle weniger als eine Autostunde von Roses entfernt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosesrentals.com\/de\/mittelalterliche-dorfer-an-der-costa-brava-roses\/","og_locale":"de_DE","og_type":"article","og_title":"Villages m\u00e9di\u00e9vaux \u00e0 visiter depuis Roses","og_description":"D\u00e9couvrez les plus beaux villages m\u00e9di\u00e9vaux de la Costa Brava, tous accessibles en moins d'une heure depuis Roses.","og_url":"https:\/\/www.rosesrentals.com\/de\/mittelalterliche-dorfer-an-der-costa-brava-roses\/","og_site_name":"Roses Rentals","article_publisher":"https:\/\/www.facebook.com\/rosesrentals","article_author":"https:\/\/www.facebook.com\/rosesrentals","article_published_time":"2026-04-17T12:44:53+00:00","article_modified_time":"2026-05-12T14:27:33+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/monells-3.jpg","type":"image\/jpeg"}],"author":"Philippe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/","url":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/","name":"In der N\u00e4he von Rosas: mittelalterliche D\u00f6rfer Costa Brava | Roses Rentals","isPartOf":{"@id":"https:\/\/www.rosesrentals.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/#primaryimage"},"image":{"@id":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/monells-3.jpg","datePublished":"2026-04-17T12:44:53+00:00","dateModified":"2026-05-12T14:27:33+00:00","description":"Entdecken Sie die sch\u00f6nsten mittelalterlichen D\u00f6rfer der Costa Brava, alle weniger als eine Autostunde von Roses entfernt.","breadcrumb":{"@id":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/#primaryimage","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/monells-3.jpg","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2026\/04\/monells-3.jpg","width":888,"height":500,"caption":"villages m\u00e9di\u00e9vaux Costa Brava"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rosesrentals.com\/"},{"@type":"ListItem","position":2,"name":"Villages m\u00e9di\u00e9vaux \u00e0 visiter depuis Roses"}]},{"@type":"WebSite","@id":"https:\/\/www.rosesrentals.com\/#website","url":"https:\/\/www.rosesrentals.com\/","name":"rosesrentals.com","description":"Ferienwohnung Roses Costa Brava | Apartments mit Meerblick - Roses Rentals","publisher":{"@id":"https:\/\/www.rosesrentals.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosesrentals.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/www.rosesrentals.com\/#organization","name":"Rosenvermietung","url":"https:\/\/www.rosesrentals.com\/","logo":{"@id":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/rosesrentals","https:\/\/www.instagram.com\/rosesrentals"],"description":"Roses Rentals ist eine Direktvermietung von Ferienwohnungen mit zwei Apartments mit Meerblick in Roses (Roses) an der Costa Brava in Katalonien, Spanien. Unsere Apartments befinden sich im Wohnviertel Canyelles Petites, nur zwei Gehminuten vom Strand entfernt, und bieten Platz f\u00fcr bis zu 4 Personen in einer ruhigen und authentischen Umgebung. Terrassen mit Meerblick, Parkplatz inklusive, selbstst\u00e4ndiger Check-in. Direktbuchung ohne Plattformgeb\u00fchren, Bestpreise garantiert. Ideal f\u00fcr einen Urlaub mit der Familie oder zu zweit an der Costa Brava.","telephone":[],"openingHoursSpecification":[]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rosesrentals.com\/villages-medievaux-costa-brava-roses\/#local-main-organization-logo","url":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","contentUrl":"https:\/\/www.rosesrentals.com\/wp-content\/uploads\/2023\/04\/rosesrentals.com_.png","width":150,"height":150,"caption":"roses Rentals"}]}},"_links":{"self":[{"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/posts\/3537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/comments?post=3537"}],"version-history":[{"count":23,"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/posts\/3537\/revisions"}],"predecessor-version":[{"id":4276,"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/posts\/3537\/revisions\/4276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/media\/3541"}],"wp:attachment":[{"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/media?parent=3537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/categories?post=3537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosesrentals.com\/de\/wp-json\/wp\/v2\/tags?post=3537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}